{"id":3046,"date":"2025-10-14T12:52:39","date_gmt":"2025-10-14T10:52:39","guid":{"rendered":"https:\/\/www.vitalibera.org\/community\/?p=3046"},"modified":"2025-10-14T13:07:55","modified_gmt":"2025-10-14T11:07:55","slug":"medikamentendosierer-fuer-eine-woche","status":"publish","type":"post","link":"http:\/\/www.vitalibera.org\/community\/2025\/10\/14\/medikamentendosierer-fuer-eine-woche\/","title":{"rendered":"Medikamentendosierer f\u00fcr eine Woche"},"content":{"rendered":"\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/509.001999_gr.jpg\" alt=\"\" class=\"wp-image-3047 size-full\" srcset=\"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/509.001999_gr.jpg 600w, http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/509.001999_gr-300x300.jpg 300w, http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/509.001999_gr-150x150.jpg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Sichere und &uuml;bersichtliche <a href=\"http:\/\/www.vitalibera.org\/community\/2026\/07\/28\/fremde-hilfe-in-der-oeffentlichkeit-bei-sturzsituation-mit-hemiplegie\/\"><font color=\"blue\"><img src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/images\/link.png\" width=\"20\" height=\"20\"><u>Hilfe<\/u><\/font><\/a> f&uuml;r alle Menschen, die regelm&auml;ssig Arzneimittel einnehmen.<\/p>\n\n\n\n<p>Sp&uuml;lmaschinengeeignet bis max 50&deg;C<\/p>\n\n\n\n<p>praktisch und sicher<\/p>\n\n\n\n<p>Wochen-Dosierer, separate Tagesration<\/p>\n\n\n\n<p>ideal auch f&uuml;r unterwegs<\/p>\n\n\n\n<p><a href=\"https:\/\/www.careproduct.ch\/de\/produkt\/medi-7-medikamentendosierung\" target=\"_blank\" rel=\"noreferrer noopener\">Zum Angebot<\/a><\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sichere und \u00fcbersichtliche Hilfe f\u00fcr alle Menschen, die regelm\u00e4ssig Arzneimittel einnehmen. Sp\u00fclmaschinengeeignet bis max 50\u00b0C praktisch und sicher Wochen-Dosierer, separate Tagesration ideal auch f\u00fcr unterwegs Zum Angebot<\/p>\n","protected":false},"author":1,"featured_media":3047,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"yes","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[226,227],"tags":[],"class_list":["post-3046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hilfsmittel-fuer-pflegende","category-medizinische-hilfen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Medikamentendosierer f\u00fcr eine Woche - vitalibera.org<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"http:\/\/www.vitalibera.org\/community\/2025\/10\/14\/medikamentendosierer-fuer-eine-woche\/\" \/>\r\n<meta property=\"og:locale\" content=\"de_DE\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Medikamentendosierer f\u00fcr eine Woche - vitalibera.org\" \/>\r\n<meta property=\"og:description\" content=\"Sichere und \u00fcbersichtliche Hilfe f\u00fcr alle Menschen, die regelm\u00e4ssig Arzneimittel einnehmen. Sp\u00fclmaschinengeeignet bis max 50\u00b0C praktisch und sicher Wochen-Dosierer, separate Tagesration ideal auch f\u00fcr unterwegs Zum Angebot\" \/>\r\n<meta property=\"og:url\" content=\"http:\/\/www.vitalibera.org\/community\/2025\/10\/14\/medikamentendosierer-fuer-eine-woche\/\" \/>\r\n<meta property=\"og:site_name\" content=\"vitalibera.org\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/2997085857140235\" \/>\r\n<meta property=\"article:published_time\" content=\"2025-10-14T10:52:39+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-10-14T11:07:55+00:00\" \/>\r\n<meta property=\"og:image\" content=\"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/509.001999_gr.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"600\" \/>\r\n\t<meta property=\"og:image:height\" content=\"600\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"admin\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/10\\\/14\\\/medikamentendosierer-fuer-eine-woche\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/10\\\/14\\\/medikamentendosierer-fuer-eine-woche\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/person\\\/c535fa8d561f7f8ca425ced40d87e582\"},\"headline\":\"Medikamentendosierer f\u00fcr eine Woche\",\"datePublished\":\"2025-10-14T10:52:39+00:00\",\"dateModified\":\"2025-10-14T11:07:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/10\\\/14\\\/medikamentendosierer-fuer-eine-woche\\\/\"},\"wordCount\":36,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/10\\\/14\\\/medikamentendosierer-fuer-eine-woche\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/509.001999_gr.jpg\",\"articleSection\":[\"Hilfsmittel f\u00fcr Pflegende\",\"Medizinische Hilfen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/10\\\/14\\\/medikamentendosierer-fuer-eine-woche\\\/\",\"url\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/10\\\/14\\\/medikamentendosierer-fuer-eine-woche\\\/\",\"name\":\"Medikamentendosierer f\u00fcr eine Woche - vitalibera.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/10\\\/14\\\/medikamentendosierer-fuer-eine-woche\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/10\\\/14\\\/medikamentendosierer-fuer-eine-woche\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/509.001999_gr.jpg\",\"datePublished\":\"2025-10-14T10:52:39+00:00\",\"dateModified\":\"2025-10-14T11:07:55+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/10\\\/14\\\/medikamentendosierer-fuer-eine-woche\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/10\\\/14\\\/medikamentendosierer-fuer-eine-woche\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/10\\\/14\\\/medikamentendosierer-fuer-eine-woche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medikamentendosierer f\u00fcr eine Woche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#website\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\",\"name\":\"vitalibera.org\",\"description\":\"Mit einer Einschr&auml;nkung gestaltet sich das Leben im Alltag oft schwieriger - hier berichten wir &uuml;ber unsere Erfahrungen und Hilfsmittel um den Alltag so unbeschwert und unkompliziert wie nur m&ouml;glich geniessen zu k&ouml;nnen. Dabei richten wir unseren Fokus gezielt auf Selbst&auml;ndigkeit, Eigenst&auml;ndigkeit und Selbstbestimmung.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#organization\",\"name\":\"vitalibera.org\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-banner.png\",\"contentUrl\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-banner.png\",\"width\":991,\"height\":150,\"caption\":\"vitalibera.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/2997085857140235\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/person\\\/c535fa8d561f7f8ca425ced40d87e582\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/0.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"http:\\\/\\\/0.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"http:\\\/\\\/0.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"admin\"},\"description\":\"admin\",\"sameAs\":[\"http:\\\/\\\/www.vitalibera.org\\\/community\"],\"url\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/author\\\/admin\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Medikamentendosierer f\u00fcr eine Woche - vitalibera.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.vitalibera.org\/community\/2025\/10\/14\/medikamentendosierer-fuer-eine-woche\/","og_locale":"de_DE","og_type":"article","og_title":"Medikamentendosierer f\u00fcr eine Woche - vitalibera.org","og_description":"Sichere und \u00fcbersichtliche Hilfe f\u00fcr alle Menschen, die regelm\u00e4ssig Arzneimittel einnehmen. Sp\u00fclmaschinengeeignet bis max 50\u00b0C praktisch und sicher Wochen-Dosierer, separate Tagesration ideal auch f\u00fcr unterwegs Zum Angebot","og_url":"http:\/\/www.vitalibera.org\/community\/2025\/10\/14\/medikamentendosierer-fuer-eine-woche\/","og_site_name":"vitalibera.org","article_publisher":"https:\/\/www.facebook.com\/groups\/2997085857140235","article_published_time":"2025-10-14T10:52:39+00:00","article_modified_time":"2025-10-14T11:07:55+00:00","og_image":[{"width":600,"height":600,"url":"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/509.001999_gr.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.vitalibera.org\/community\/2025\/10\/14\/medikamentendosierer-fuer-eine-woche\/#article","isPartOf":{"@id":"http:\/\/www.vitalibera.org\/community\/2025\/10\/14\/medikamentendosierer-fuer-eine-woche\/"},"author":{"name":"admin","@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/person\/c535fa8d561f7f8ca425ced40d87e582"},"headline":"Medikamentendosierer f\u00fcr eine Woche","datePublished":"2025-10-14T10:52:39+00:00","dateModified":"2025-10-14T11:07:55+00:00","mainEntityOfPage":{"@id":"http:\/\/www.vitalibera.org\/community\/2025\/10\/14\/medikamentendosierer-fuer-eine-woche\/"},"wordCount":36,"publisher":{"@id":"https:\/\/www.vitalibera.org\/community\/#organization"},"image":{"@id":"http:\/\/www.vitalibera.org\/community\/2025\/10\/14\/medikamentendosierer-fuer-eine-woche\/#primaryimage"},"thumbnailUrl":"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/509.001999_gr.jpg","articleSection":["Hilfsmittel f\u00fcr Pflegende","Medizinische Hilfen"],"inLanguage":"de"},{"@type":"WebPage","@id":"http:\/\/www.vitalibera.org\/community\/2025\/10\/14\/medikamentendosierer-fuer-eine-woche\/","url":"http:\/\/www.vitalibera.org\/community\/2025\/10\/14\/medikamentendosierer-fuer-eine-woche\/","name":"Medikamentendosierer f\u00fcr eine Woche - vitalibera.org","isPartOf":{"@id":"https:\/\/www.vitalibera.org\/community\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.vitalibera.org\/community\/2025\/10\/14\/medikamentendosierer-fuer-eine-woche\/#primaryimage"},"image":{"@id":"http:\/\/www.vitalibera.org\/community\/2025\/10\/14\/medikamentendosierer-fuer-eine-woche\/#primaryimage"},"thumbnailUrl":"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/509.001999_gr.jpg","datePublished":"2025-10-14T10:52:39+00:00","dateModified":"2025-10-14T11:07:55+00:00","breadcrumb":{"@id":"http:\/\/www.vitalibera.org\/community\/2025\/10\/14\/medikamentendosierer-fuer-eine-woche\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.vitalibera.org\/community\/2025\/10\/14\/medikamentendosierer-fuer-eine-woche\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.vitalibera.org\/community\/2025\/10\/14\/medikamentendosierer-fuer-eine-woche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.vitalibera.org\/community\/"},{"@type":"ListItem","position":2,"name":"Medikamentendosierer f\u00fcr eine Woche"}]},{"@type":"WebSite","@id":"https:\/\/www.vitalibera.org\/community\/#website","url":"https:\/\/www.vitalibera.org\/community\/","name":"vitalibera.org","description":"Mit einer Einschr&auml;nkung gestaltet sich das Leben im Alltag oft schwieriger - hier berichten wir &uuml;ber unsere Erfahrungen und Hilfsmittel um den Alltag so unbeschwert und unkompliziert wie nur m&ouml;glich geniessen zu k&ouml;nnen. Dabei richten wir unseren Fokus gezielt auf Selbst&auml;ndigkeit, Eigenst&auml;ndigkeit und Selbstbestimmung.","publisher":{"@id":"https:\/\/www.vitalibera.org\/community\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vitalibera.org\/community\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.vitalibera.org\/community\/#organization","name":"vitalibera.org","url":"https:\/\/www.vitalibera.org\/community\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/logo\/image\/","url":"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/cropped-banner.png","contentUrl":"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/cropped-banner.png","width":991,"height":150,"caption":"vitalibera.org"},"image":{"@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/2997085857140235"]},{"@type":"Person","@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/person\/c535fa8d561f7f8ca425ced40d87e582","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/0.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"http:\/\/0.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"http:\/\/0.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"admin"},"description":"admin","sameAs":["http:\/\/www.vitalibera.org\/community"],"url":"http:\/\/www.vitalibera.org\/community\/author\/admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":4475,"url":"http:\/\/www.vitalibera.org\/community\/2025\/11\/23\/schwangerschaft-nach-einem-schlaganfall\/","url_meta":{"origin":3046,"position":0},"title":"Schwangerschaft nach einem Schlaganfall","author":"Andreas Jecklin","date":"23 November, 2025","format":false,"excerpt":"Eine Schwangerschaft nach einem Schlaganfall ist m\u00f6glich, erfordert jedoch eine sorgf\u00e4ltige medizinische Planung und eine engmaschige Betreuung vor, w\u00e4hrend und nach der Schwangerschaft. W\u00e4hrend Schwangerschaften das Schlaganfallrisiko erh\u00f6hen k\u00f6nnen, ist das Rezidivrisiko nach einem Schlaganfall in den ersten Jahren im Allgemeinen nicht sehr hoch, und viele Frauen k\u00f6nnen mit der\u2026","rel":"","context":"In &quot;Kinder und Babys&quot;","block_context":{"text":"Kinder und Babys","link":"http:\/\/www.vitalibera.org\/community\/category\/beitraege\/eingeschraenkt-im-alltag\/alltag\/kinder-und-babys\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/11\/schwangerschaft-und-stillzeit.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/11\/schwangerschaft-und-stillzeit.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/11\/schwangerschaft-und-stillzeit.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/11\/schwangerschaft-und-stillzeit.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/11\/schwangerschaft-und-stillzeit.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/11\/schwangerschaft-und-stillzeit.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":6733,"url":"http:\/\/www.vitalibera.org\/community\/2026\/04\/14\/was-du-noch-waehrend-der-reha-in-die-wege-leiten-kannst\/","url_meta":{"origin":3046,"position":1},"title":"Was du noch w\u00e4hrend der REHA in die Wege leiten kannst","author":"Andreas Jecklin","date":"14 April, 2026","format":false,"excerpt":"In der Akut\u2011Reha kann extrem viel vorbereitet werden, damit der \u00dcbergang nach Hause nicht chaotisch wird. Und genau diese Phase ist der Moment, in dem Strukturen, Antr\u00e4ge und Weichenstellungen am leichtesten gelingen \u2014 weil das gesamte Team noch greifbar ist. Medizin & Therapien f\u00fcr die Zeit nach der Reha sichern\u2026","rel":"","context":"In &quot;Hilfe f\u00fcr Angeh\u00f6rige&quot;","block_context":{"text":"Hilfe f\u00fcr Angeh\u00f6rige","link":"http:\/\/www.vitalibera.org\/community\/category\/hilfe-fuer-angehoerige\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/04\/todoinreha3.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7728,"url":"http:\/\/www.vitalibera.org\/community\/2026\/06\/03\/selbststaendiges-medikamentenmanagement-trotz-hirnverletzung\/","url_meta":{"origin":3046,"position":2},"title":"Selbstst\u00e4ndiges Medikamentenmanagement trotz  Hirnverletzung","author":"admin","date":"3 Juni, 2026","format":false,"excerpt":"Die eigenst\u00e4ndige Einnahme von Medikamenten ist ein wichtiger Bestandteil der Gesundheit und des Alltags. F\u00fcr Menschen mit einer neurologischen Hirnverletzung kann dies jedoch eine besondere Herausforderung darstellen. Probleme mit Ged\u00e4chtnis, Konzentration oder Struktur k\u00f6nnen dazu f\u00fchren, dass Medikamente vergessen, falsch eingenommen oder unsicher gehandhabt werden. Umso wichtiger ist ein einfaches,\u2026","rel":"","context":"In &quot;Medizinische Hilfen&quot;","block_context":{"text":"Medizinische Hilfen","link":"http:\/\/www.vitalibera.org\/community\/category\/beitraege\/eingeschraenkt-im-alltag\/medizinische-hilfen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/06\/medi89898.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5511,"url":"http:\/\/www.vitalibera.org\/community\/2026\/02\/10\/schleppendes-bein-nach-schlaganfall\/","url_meta":{"origin":3046,"position":3},"title":"Schleppendes Bein nach Schlaganfall","author":"Andreas Jecklin","date":"10 Februar, 2026","format":false,"excerpt":"Ein schleppendes Bein (oft mit Fu\u00dfheberschw\u00e4che) nach einem Schlaganfall ist\u00a0meist Folge einer\u00a0spastischen Bewegungsst\u00f6rung, bei der Muskeln verkrampfen, da das Gehirn Signale nicht mehr richtig steuert. Diese Spastik entwickelt sich oft verz\u00f6gert (Wochen\/Monate danach), f\u00fchrt zu Schmerzen und verlangt fr\u00fchzeitige Physiotherapie,\u00a0Orthesen,\u00a0Botox\u00a0oder Medikamente.\u00a0 Ursachen und Symptome: Spastik:\u00a0Sch\u00e4digung des zentralen Nervensystems f\u00fchrt zu\u2026","rel":"","context":"In &quot;Physiotherapie&quot;","block_context":{"text":"Physiotherapie","link":"http:\/\/www.vitalibera.org\/community\/category\/eigentherapie-und-trainings\/physio\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/02\/draggingleg.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5138,"url":"http:\/\/www.vitalibera.org\/community\/2026\/01\/14\/treppensteigen-mit-spastik\/","url_meta":{"origin":3046,"position":4},"title":"Treppensteigen mit Spastik","author":"Andreas Jecklin","date":"14 Januar, 2026","format":false,"excerpt":"Treppensteigen mit Spastik nach einem Schlaganfall ist schwierig, weil die \u00fcberh\u00f6hte Muskelspannung (Spastik) die Bewegung einschr\u00e4nkt und verkrampft, was zu Steifigkeit, Kontrollverlust und Schmerzen f\u00fchren kann, aber durch intensive Physiotherapie, Dehn\u00fcbungen, gezielte Kr\u00e4ftigung und manchmal Medikamente gut behandelbar ist, um nat\u00fcrliche Bewegungsabl\u00e4ufe zu f\u00f6rdern und Folgesch\u00e4den zu minimieren. Wichtig sind\u2026","rel":"","context":"In &quot;Physiotherapie&quot;","block_context":{"text":"Physiotherapie","link":"http:\/\/www.vitalibera.org\/community\/category\/eigentherapie-und-trainings\/physio\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/01\/treppen.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/01\/treppen.png?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/01\/treppen.png?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/01\/treppen.png?resize=700%2C400 2x"},"classes":[]},{"id":4730,"url":"http:\/\/www.vitalibera.org\/community\/2025\/12\/24\/4730\/","url_meta":{"origin":3046,"position":5},"title":"Verhinderungspflege","author":"Andreas Jecklin","date":"24 Dezember, 2025","format":false,"excerpt":"Verhinderungspflege\u00a0ist eine\u00a0Leistung der deutschen Pflegeversicherung, die die h\u00e4usliche Pflege sicherstellt, wenn die eigentliche Pflegeperson (Angeh\u00f6riger, Freund) vor\u00fcbergehend ausf\u00e4llt, etwa wegen Krankheit, Urlaub oder Beruf.Sie wird f\u00fcr bis zu sechs Wochen pro Jahr gew\u00e4hrt (bei jungen Pflegebed\u00fcrftigen unter 25 Jahren mit Pflegegrad 4\/5 bis zu 8 Wochen) und die Kosten f\u00fcr\u2026","rel":"","context":"In &quot;Hilfe f\u00fcr Angeh\u00f6rige&quot;","block_context":{"text":"Hilfe f\u00fcr Angeh\u00f6rige","link":"http:\/\/www.vitalibera.org\/community\/category\/hilfe-fuer-angehoerige\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/12\/verhinderungs.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/12\/verhinderungs.png?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/12\/verhinderungs.png?resize=525%2C300 1.5x"},"classes":[]}],"jetpack_featured_media_url":"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/509.001999_gr.jpg","_links":{"self":[{"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/posts\/3046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/comments?post=3046"}],"version-history":[{"count":0,"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/posts\/3046\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/media\/3047"}],"wp:attachment":[{"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/media?parent=3046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/categories?post=3046"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/tags?post=3046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}