{"id":4767,"date":"2025-12-25T21:17:51","date_gmt":"2025-12-25T20:17:51","guid":{"rendered":"https:\/\/www.vitalibera.org\/community\/?p=4767"},"modified":"2025-12-25T21:18:49","modified_gmt":"2025-12-25T20:18:49","slug":"selbstbestimmtes-leben-trotz-handicap-zuhause","status":"publish","type":"post","link":"http:\/\/www.vitalibera.org\/community\/2025\/12\/25\/selbstbestimmtes-leben-trotz-handicap-zuhause\/","title":{"rendered":"Selbstbestimmtes Leben trotz Handicap zuhause"},"content":{"rendered":"\n<p>Ein selbstbestimmtes Leben trotz Handicap zuhause ist durch&nbsp;<strong>barrierefreie Anpassungen,&nbsp;flexible Assistenzleistungen&nbsp;(Pers&ouml;nlicher Budget, Begleitetes Wohnen, <a href=\"http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/spitex\/\" target=\"_self\" title=\"Spitex steht f&uuml;r &bdquo;spitalexterne Hilfe und Pflege&ldquo; und umfasst Dienstleistungen, die Menschen jeden Alters zu Hause pflegen, betreuen und unterst&uuml;tzen, wenn diese krank, behindert, alt oder in einer schwierigen Lebenssituation sind. Ziel ist es, die Selbstst&auml;ndigkeit zu erhalten und den Verbleib im vertrauten Umfeld zu erm&ouml;glichen\" class=\"encyclopedia\">Spitex<\/a>),&nbsp;soziale Einbindung&nbsp;(Selbsthilfegruppen, Vereine) und spezialisierte Beratungsstellen (EUTB)<\/strong>&nbsp;m&ouml;glich, wobei der&nbsp;<strong>Assistenzbeitrag<\/strong>&nbsp;die wichtigste Finanzierungsgrundlage ist, um Unterst&uuml;tzungspersonal selbst zu engagieren und die eigene Wohnung zu gestalten. <\/p>\n\n\n\n<p>Wichtig ist der Fokus auf die eigene Wahl der Wohnform, um ein m&ouml;glichst autonomes Leben zu f&uuml;hren, auch wenn die Suche nach bezahlbarem, barrierefreiem Wohnraum eine Herausforderung sein kann.&nbsp;<\/p>\n\n\n\n<p>Wichtige Bausteine f&uuml;r das Leben zuhause:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Barrierefreiheit:<\/strong>&nbsp;Anpassung der Wohnung an individuelle Bed&uuml;rfnisse, was oft eine Voraussetzung ist.<\/li>\n\n\n\n<li><strong>Assistenz:<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>Pers&ouml;nliches Budget\/Assistenzbeitrag:<\/strong>&nbsp;Erm&ouml;glicht die Finanzierung von Assistenzkr&auml;ften f&uuml;r den <a href=\"http:\/\/www.vitalibera.org\/community\/2026\/04\/30\/lapstacker-transport-gurtsystem-fuer-rollstuehle\/\"><font color=\"blue\"><img src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/images\/link.png\" width=\"20\" height=\"20\"><u>Alltag<\/u><\/font><\/a> (Einkaufen, <a href=\"http:\/\/www.vitalibera.org\/community\/2026\/07\/09\/muellentsorgung-und-recycling-trotz-einschraenkungen-nach-einer-hirnverletzung\/\"><font color=\"blue\"><img src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/images\/link.png\" width=\"20\" height=\"20\"><u>Haushalt<\/u><\/font><\/a>, Arztbesuche).<\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.google.com\/search?q=Begleitetes+Wohnen&amp;rlz=1C1ONGR_enCH1115CH1115&amp;oq=&amp;gs_lcrp=EgZjaHJvbWUqCQgBEEUYOxjCAzIJCAAQRRg7GMIDMgkIARBFGDsYwgMyCQgCEEUYOxjCAzIJCAMQRRg7GMIDMgkIBBBFGDsYwgMyCQgFEEUYOxjCAzIJCAYQRRg7GMIDMgkIBxBFGDsYwgPSAQoyODg3NGowajE1qAIIsAIB8QWiRQl0j7LVffEFokUJdI-y1X0&amp;sourceid=chrome&amp;ie=UTF-8&amp;mstk=AUtExfBY-HljvKVn1LXhHPCr-2Ik4B6jwoygjFGSUE5o-7DNXHoybbD_JHGhzBdELAZZcEhaF7fGuKOrjPshdRontGeZKoOF_1zKnRgxVzZ8YhSpkEoa7L0bbwQ9x1q3R3XWay93PKoQJNj-VoyQB5BwxShn01E4owZPcE6lMSc483W9ISM&amp;csui=3&amp;ved=2ahUKEwiU99mXxtmRAxW-3AIHHXhdBjgQgK4QegQIAxAE\" target=\"_blank\" rel=\"noreferrer noopener\">Begleitetes Wohnen<\/a>:<\/strong>&nbsp;Regelm&auml;ssige Besuche durch eine Begleitperson zur Unterst&uuml;tzung in verschiedenen Lebensbereichen.<\/li>\n\n\n\n<li><strong><a href=\"http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/spitex\/\" target=\"_self\" title=\"Spitex steht f&uuml;r &bdquo;spitalexterne Hilfe und Pflege&ldquo; und umfasst Dienstleistungen, die Menschen jeden Alters zu Hause pflegen, betreuen und unterst&uuml;tzen, wenn diese krank, behindert, alt oder in einer schwierigen Lebenssituation sind. Ziel ist es, die Selbstst&auml;ndigkeit zu erhalten und den Verbleib im vertrauten Umfeld zu erm&ouml;glichen\" class=\"encyclopedia\">Spitex<\/a>:<\/strong>&nbsp;Pflegerische und hauswirtschaftliche Unterst&uuml;tzung, um die Selbstst&auml;ndigkeit zu erhalten.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Finanzielle Unterst&uuml;tzung:<\/strong>&nbsp;Der Assistenzbeitrag ist zentral, um die ben&ouml;tigte <a href=\"http:\/\/www.vitalibera.org\/community\/2026\/07\/28\/fremde-hilfe-in-der-oeffentlichkeit-bei-sturzsituation-mit-hemiplegie\/\"><font color=\"blue\"><img src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/images\/link.png\" width=\"20\" height=\"20\"><u>Hilfe<\/u><\/font><\/a> selbst zu organisieren.<\/li>\n\n\n\n<li><strong>Soziale Integration:<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>Selbsthilfegruppen und Vereine:<\/strong>&nbsp;Austausch mit Gleichgesinnten und Tipps f&uuml;r den Alltag.<\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.google.com\/search?q=Sozialraumorientierung&amp;rlz=1C1ONGR_enCH1115CH1115&amp;oq=&amp;gs_lcrp=EgZjaHJvbWUqCQgBEEUYOxjCAzIJCAAQRRg7GMIDMgkIARBFGDsYwgMyCQgCEEUYOxjCAzIJCAMQRRg7GMIDMgkIBBBFGDsYwgMyCQgFEEUYOxjCAzIJCAYQRRg7GMIDMgkIBxBFGDsYwgPSAQoyODg3NGowajE1qAIIsAIB8QWiRQl0j7LVffEFokUJdI-y1X0&amp;sourceid=chrome&amp;ie=UTF-8&amp;mstk=AUtExfBY-HljvKVn1LXhHPCr-2Ik4B6jwoygjFGSUE5o-7DNXHoybbD_JHGhzBdELAZZcEhaF7fGuKOrjPshdRontGeZKoOF_1zKnRgxVzZ8YhSpkEoa7L0bbwQ9x1q3R3XWay93PKoQJNj-VoyQB5BwxShn01E4owZPcE6lMSc483W9ISM&amp;csui=3&amp;ved=2ahUKEwiU99mXxtmRAxW-3AIHHXhdBjgQgK4QegQIAxAK\" target=\"_blank\" rel=\"noreferrer noopener\">Sozialraumorientierung<\/a>:<\/strong>&nbsp;Einbindung in die Nachbarschaft, um Isolation zu vermeiden.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Beratung:<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>EUTB-Beratungsstellen (Erg&auml;nzende unabh&auml;ngige Teilhabeberatung):<\/strong>&nbsp;Bieten umfassende Beratung, oft durch Menschen mit Behinderung.<\/li>\n\n\n\n<li><strong>Wohnschulen:<\/strong>&nbsp;Vermitteln F&auml;higkeiten f&uuml;r ein selbstst&auml;ndiges Leben.&nbsp;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p>Fazit:<\/p>\n\n\n\n<p>Der Weg zu einem selbstbestimmten Leben zuhause erfordert oft die Kombination verschiedener Hilfen. Der Schl&uuml;ssel liegt darin, die eigenen W&uuml;nsche zu definieren und aktiv nach den passenden finanziellen Mitteln (wie dem Assistenzbeitrag) und Dienstleistern (wie Assistenz oder <a href=\"http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/spitex\/\" target=\"_self\" title=\"Spitex steht f&uuml;r &bdquo;spitalexterne Hilfe und Pflege&ldquo; und umfasst Dienstleistungen, die Menschen jeden Alters zu Hause pflegen, betreuen und unterst&uuml;tzen, wenn diese krank, behindert, alt oder in einer schwierigen Lebenssituation sind. Ziel ist es, die Selbstst&auml;ndigkeit zu erhalten und den Verbleib im vertrauten Umfeld zu erm&ouml;glichen\" class=\"encyclopedia\">Spitex<\/a>) zu suchen, um die eigene Wohnung nach den eigenen Vorstellungen zu gestalten.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein selbstbestimmtes Leben trotz Handicap zuhause ist durch\u00a0barrierefreie Anpassungen,\u00a0flexible Assistenzleistungen\u00a0(Pers\u00f6nlicher Budget, Begleitetes Wohnen, Spitex),\u00a0soziale Einbindung\u00a0(Selbsthilfegruppen, Vereine) und spezialisierte Beratungsstellen (EUTB)\u00a0m\u00f6glich, wobei der\u00a0Assistenzbeitrag\u00a0die wichtigste Finanzierungsgrundlage ist, um Unterst\u00fctzungspersonal selbst zu engagieren und die eigene Wohnung zu gestalten. Wichtig ist der Fokus auf die eigene Wahl der Wohnform, um ein m\u00f6glichst autonomes Leben zu f\u00fchren, auch wenn &#8230; <a title=\"Selbstbestimmtes Leben trotz Handicap zuhause\" class=\"read-more\" href=\"http:\/\/www.vitalibera.org\/community\/2025\/12\/25\/selbstbestimmtes-leben-trotz-handicap-zuhause\/\" aria-label=\"Mehr Informationen \u00fcber Selbstbestimmtes Leben trotz Handicap zuhause\">Weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":4768,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"yes","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[42,225],"tags":[],"class_list":["post-4767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alltag","category-hilfe-fuer-angehoerige"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Selbstbestimmtes Leben trotz Handicap zuhause - vitalibera.org<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"http:\/\/www.vitalibera.org\/community\/2025\/12\/25\/selbstbestimmtes-leben-trotz-handicap-zuhause\/\" \/>\r\n<meta property=\"og:locale\" content=\"de_DE\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Selbstbestimmtes Leben trotz Handicap zuhause - vitalibera.org\" \/>\r\n<meta property=\"og:description\" content=\"Ein selbstbestimmtes Leben trotz Handicap zuhause ist durch\u00a0barrierefreie Anpassungen,\u00a0flexible Assistenzleistungen\u00a0(Pers\u00f6nlicher Budget, Begleitetes Wohnen, Spitex),\u00a0soziale Einbindung\u00a0(Selbsthilfegruppen, Vereine) und spezialisierte Beratungsstellen (EUTB)\u00a0m\u00f6glich, wobei der\u00a0Assistenzbeitrag\u00a0die wichtigste Finanzierungsgrundlage ist, um Unterst\u00fctzungspersonal selbst zu engagieren und die eigene Wohnung zu gestalten. Wichtig ist der Fokus auf die eigene Wahl der Wohnform, um ein m\u00f6glichst autonomes Leben zu f\u00fchren, auch wenn ... Weiterlesen\" \/>\r\n<meta property=\"og:url\" content=\"http:\/\/www.vitalibera.org\/community\/2025\/12\/25\/selbstbestimmtes-leben-trotz-handicap-zuhause\/\" \/>\r\n<meta property=\"og:site_name\" content=\"vitalibera.org\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/2997085857140235\" \/>\r\n<meta property=\"article:published_time\" content=\"2025-12-25T20:17:51+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-12-25T20:18:49+00:00\" \/>\r\n<meta property=\"og:image\" content=\"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/12\/Screenshot-2025-12-25-211635.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"618\" \/>\r\n\t<meta property=\"og:image:height\" content=\"413\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"author\" content=\"Andreas Jecklin\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andreas Jecklin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/12\\\/25\\\/selbstbestimmtes-leben-trotz-handicap-zuhause\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/12\\\/25\\\/selbstbestimmtes-leben-trotz-handicap-zuhause\\\/\"},\"author\":{\"name\":\"Andreas Jecklin\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/person\\\/6712387298421f222ff6d0a2e22c1534\"},\"headline\":\"Selbstbestimmtes Leben trotz Handicap zuhause\",\"datePublished\":\"2025-12-25T20:17:51+00:00\",\"dateModified\":\"2025-12-25T20:18:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/12\\\/25\\\/selbstbestimmtes-leben-trotz-handicap-zuhause\\\/\"},\"wordCount\":265,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/12\\\/25\\\/selbstbestimmtes-leben-trotz-handicap-zuhause\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Screenshot-2025-12-25-211635.png\",\"articleSection\":[\"Alltag\",\"Hilfe f\u00fcr Angeh\u00f6rige\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/12\\\/25\\\/selbstbestimmtes-leben-trotz-handicap-zuhause\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/12\\\/25\\\/selbstbestimmtes-leben-trotz-handicap-zuhause\\\/\",\"url\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/12\\\/25\\\/selbstbestimmtes-leben-trotz-handicap-zuhause\\\/\",\"name\":\"Selbstbestimmtes Leben trotz Handicap zuhause - vitalibera.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/12\\\/25\\\/selbstbestimmtes-leben-trotz-handicap-zuhause\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/12\\\/25\\\/selbstbestimmtes-leben-trotz-handicap-zuhause\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Screenshot-2025-12-25-211635.png\",\"datePublished\":\"2025-12-25T20:17:51+00:00\",\"dateModified\":\"2025-12-25T20:18:49+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/12\\\/25\\\/selbstbestimmtes-leben-trotz-handicap-zuhause\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/12\\\/25\\\/selbstbestimmtes-leben-trotz-handicap-zuhause\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2025\\\/12\\\/25\\\/selbstbestimmtes-leben-trotz-handicap-zuhause\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Selbstbestimmtes Leben trotz Handicap zuhause\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#website\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\",\"name\":\"vitalibera.org\",\"description\":\"Mit einer Einschr&auml;nkung gestaltet sich das Leben im Alltag oft schwieriger - hier berichten wir &uuml;ber unsere Erfahrungen und Hilfsmittel um den Alltag so unbeschwert und unkompliziert wie nur m&ouml;glich geniessen zu k&ouml;nnen. Dabei richten wir unseren Fokus gezielt auf Selbst&auml;ndigkeit, Eigenst&auml;ndigkeit und Selbstbestimmung.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#organization\",\"name\":\"vitalibera.org\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-banner.png\",\"contentUrl\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-banner.png\",\"width\":991,\"height\":150,\"caption\":\"vitalibera.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/2997085857140235\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/person\\\/6712387298421f222ff6d0a2e22c1534\",\"name\":\"Andreas Jecklin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/0.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"http:\\\/\\\/0.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"http:\\\/\\\/0.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Andreas Jecklin\"},\"description\":\"Manchen gab Gott die Kraft Dinge zu ver\u00e4ndern, mir gab er die Kraft zu ertragen was nicht mehr zu \u00e4ndern ist.\",\"url\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/author\\\/andy77\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Selbstbestimmtes Leben trotz Handicap zuhause - vitalibera.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.vitalibera.org\/community\/2025\/12\/25\/selbstbestimmtes-leben-trotz-handicap-zuhause\/","og_locale":"de_DE","og_type":"article","og_title":"Selbstbestimmtes Leben trotz Handicap zuhause - vitalibera.org","og_description":"Ein selbstbestimmtes Leben trotz Handicap zuhause ist durch\u00a0barrierefreie Anpassungen,\u00a0flexible Assistenzleistungen\u00a0(Pers\u00f6nlicher Budget, Begleitetes Wohnen, Spitex),\u00a0soziale Einbindung\u00a0(Selbsthilfegruppen, Vereine) und spezialisierte Beratungsstellen (EUTB)\u00a0m\u00f6glich, wobei der\u00a0Assistenzbeitrag\u00a0die wichtigste Finanzierungsgrundlage ist, um Unterst\u00fctzungspersonal selbst zu engagieren und die eigene Wohnung zu gestalten. Wichtig ist der Fokus auf die eigene Wahl der Wohnform, um ein m\u00f6glichst autonomes Leben zu f\u00fchren, auch wenn ... Weiterlesen","og_url":"http:\/\/www.vitalibera.org\/community\/2025\/12\/25\/selbstbestimmtes-leben-trotz-handicap-zuhause\/","og_site_name":"vitalibera.org","article_publisher":"https:\/\/www.facebook.com\/groups\/2997085857140235","article_published_time":"2025-12-25T20:17:51+00:00","article_modified_time":"2025-12-25T20:18:49+00:00","og_image":[{"width":618,"height":413,"url":"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/12\/Screenshot-2025-12-25-211635.png","type":"image\/png"}],"author":"Andreas Jecklin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Andreas Jecklin","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.vitalibera.org\/community\/2025\/12\/25\/selbstbestimmtes-leben-trotz-handicap-zuhause\/#article","isPartOf":{"@id":"http:\/\/www.vitalibera.org\/community\/2025\/12\/25\/selbstbestimmtes-leben-trotz-handicap-zuhause\/"},"author":{"name":"Andreas Jecklin","@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/person\/6712387298421f222ff6d0a2e22c1534"},"headline":"Selbstbestimmtes Leben trotz Handicap zuhause","datePublished":"2025-12-25T20:17:51+00:00","dateModified":"2025-12-25T20:18:49+00:00","mainEntityOfPage":{"@id":"http:\/\/www.vitalibera.org\/community\/2025\/12\/25\/selbstbestimmtes-leben-trotz-handicap-zuhause\/"},"wordCount":265,"commentCount":0,"publisher":{"@id":"https:\/\/www.vitalibera.org\/community\/#organization"},"image":{"@id":"http:\/\/www.vitalibera.org\/community\/2025\/12\/25\/selbstbestimmtes-leben-trotz-handicap-zuhause\/#primaryimage"},"thumbnailUrl":"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/12\/Screenshot-2025-12-25-211635.png","articleSection":["Alltag","Hilfe f\u00fcr Angeh\u00f6rige"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.vitalibera.org\/community\/2025\/12\/25\/selbstbestimmtes-leben-trotz-handicap-zuhause\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.vitalibera.org\/community\/2025\/12\/25\/selbstbestimmtes-leben-trotz-handicap-zuhause\/","url":"http:\/\/www.vitalibera.org\/community\/2025\/12\/25\/selbstbestimmtes-leben-trotz-handicap-zuhause\/","name":"Selbstbestimmtes Leben trotz Handicap zuhause - vitalibera.org","isPartOf":{"@id":"https:\/\/www.vitalibera.org\/community\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.vitalibera.org\/community\/2025\/12\/25\/selbstbestimmtes-leben-trotz-handicap-zuhause\/#primaryimage"},"image":{"@id":"http:\/\/www.vitalibera.org\/community\/2025\/12\/25\/selbstbestimmtes-leben-trotz-handicap-zuhause\/#primaryimage"},"thumbnailUrl":"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/12\/Screenshot-2025-12-25-211635.png","datePublished":"2025-12-25T20:17:51+00:00","dateModified":"2025-12-25T20:18:49+00:00","breadcrumb":{"@id":"http:\/\/www.vitalibera.org\/community\/2025\/12\/25\/selbstbestimmtes-leben-trotz-handicap-zuhause\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.vitalibera.org\/community\/2025\/12\/25\/selbstbestimmtes-leben-trotz-handicap-zuhause\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.vitalibera.org\/community\/2025\/12\/25\/selbstbestimmtes-leben-trotz-handicap-zuhause\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.vitalibera.org\/community\/"},{"@type":"ListItem","position":2,"name":"Selbstbestimmtes Leben trotz Handicap zuhause"}]},{"@type":"WebSite","@id":"https:\/\/www.vitalibera.org\/community\/#website","url":"https:\/\/www.vitalibera.org\/community\/","name":"vitalibera.org","description":"Mit einer Einschr&auml;nkung gestaltet sich das Leben im Alltag oft schwieriger - hier berichten wir &uuml;ber unsere Erfahrungen und Hilfsmittel um den Alltag so unbeschwert und unkompliziert wie nur m&ouml;glich geniessen zu k&ouml;nnen. Dabei richten wir unseren Fokus gezielt auf Selbst&auml;ndigkeit, Eigenst&auml;ndigkeit und Selbstbestimmung.","publisher":{"@id":"https:\/\/www.vitalibera.org\/community\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vitalibera.org\/community\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.vitalibera.org\/community\/#organization","name":"vitalibera.org","url":"https:\/\/www.vitalibera.org\/community\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/logo\/image\/","url":"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/cropped-banner.png","contentUrl":"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/cropped-banner.png","width":991,"height":150,"caption":"vitalibera.org"},"image":{"@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/2997085857140235"]},{"@type":"Person","@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/person\/6712387298421f222ff6d0a2e22c1534","name":"Andreas Jecklin","image":{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/0.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"http:\/\/0.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"http:\/\/0.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Andreas Jecklin"},"description":"Manchen gab Gott die Kraft Dinge zu ver\u00e4ndern, mir gab er die Kraft zu ertragen was nicht mehr zu \u00e4ndern ist.","url":"http:\/\/www.vitalibera.org\/community\/author\/andy77\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":2971,"url":"http:\/\/www.vitalibera.org\/community\/2025\/10\/12\/wohnen-mit-handicap\/","url_meta":{"origin":4767,"position":0},"title":"Wohnen mit Handicap","author":"admin","date":"12 Oktober, 2025","format":false,"excerpt":"Das Wohnen mit Behinderung stellt besondere Anforderungen an die Wohnsituation und kann entsprechend der pers\u00f6nlichen Gegebenheiten unterschiedlich geartet sein. Je nach Grad der Behinderung und pers\u00f6nlicher Pr\u00e4ferenz gibt es viele M\u00f6glichkeiten, durch die Menschen mit Behinderung Selbstst\u00e4ndigkeit, aber auch Unterst\u00fctzung und Betreuung erhalten. Viele m\u00f6chten, wenn m\u00f6glich, gern in den\u2026","rel":"","context":"In &quot;Hilfe f\u00fcr Angeh\u00f6rige&quot;","block_context":{"text":"Hilfe f\u00fcr Angeh\u00f6rige","link":"http:\/\/www.vitalibera.org\/community\/category\/hilfe-fuer-angehoerige\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/behindertengerecht_wohnen_AdobeStock_22786875.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/behindertengerecht_wohnen_AdobeStock_22786875.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/behindertengerecht_wohnen_AdobeStock_22786875.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/behindertengerecht_wohnen_AdobeStock_22786875.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/behindertengerecht_wohnen_AdobeStock_22786875.jpg?resize=1050%2C600 3x"},"classes":[]},{"id":6502,"url":"http:\/\/www.vitalibera.org\/community\/2026\/04\/03\/mein-leben-meine-regeln-love-it-or-leave-it\/","url_meta":{"origin":4767,"position":1},"title":"Mein Leben &#8211; Meine Regeln &#8211; Love it, or leave it","author":"Andreas Jecklin","date":"3 April, 2026","format":false,"excerpt":"PFLEGEHEIM? NEIN DANKE. Ich lasse mich nicht verwalten. Ich lebe. Ich entscheide. Ich geh\u00f6re nicht ins System. Ich bin kein Fall. Ich bin kein Bettplatz. Ich bin Selbstbestimmend! Ich bestehe auf meine Menschenw\u00fcrde Ich geh\u00f6re mir - niemand schreibt meine Zukunft f\u00fcr mich. Je nach Schwere der neurologischen Erkrankung ist\u2026","rel":"","context":"In &quot;Eingeschr\u00e4nkt im Alltag&quot;","block_context":{"text":"Eingeschr\u00e4nkt im Alltag","link":"http:\/\/www.vitalibera.org\/community\/category\/beitraege\/eingeschraenkt-im-alltag\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/04\/sad.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/04\/sad.png?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/04\/sad.png?resize=525%2C300 1.5x"},"classes":[]},{"id":6848,"url":"http:\/\/www.vitalibera.org\/community\/2026\/04\/19\/ich-entscheide-wo-mein-alltag-stattfindet-kein-heimzwang-punkt\/","url_meta":{"origin":4767,"position":2},"title":"Ich entscheide wo mein Alltag stattfindet &#8211; Kein Heimzwang Punkt!","author":"Andreas Jecklin","date":"19 April, 2026","format":false,"excerpt":"Du hast ein klares Recht, nicht in ein Heim zu m\u00fcssen \u2013 selbst wenn andere \u00fcberzeugt sind, es w\u00e4re \u201edas Beste\u201c. In der Schweiz gilt ein starker Grundsatz: Selbstbestimmung geht vor Fremdbestimmung. Niemand darf dich gegen deinen Willen in ein Heim dr\u00e4ngen, solange du urteilsf\u00e4hig bist. Du musst auch in\u2026","rel":"","context":"In &quot;Alltagsnavigation&quot;","block_context":{"text":"Alltagsnavigation","link":"http:\/\/www.vitalibera.org\/community\/category\/beitraege\/eingeschraenkt-im-alltag\/alltagsnavigation\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/04\/keinheim8.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3177,"url":"http:\/\/www.vitalibera.org\/community\/2025\/10\/16\/betreutes-wohnen-service-wohnen\/","url_meta":{"origin":4767,"position":3},"title":"Betreutes Wohnen \/ Service-Wohnen","author":"Andreas Jecklin","date":"16 Oktober, 2025","format":false,"excerpt":"Wer m\u00f6chte nicht so lange wie m\u00f6glich selbstst\u00e4ndig leben? Doch manchmal erfordern das zunehmende Alter oder eine Krankheit hier und da etwas Unterst\u00fctzung. Betreutes Wohnen oder Service-Wohnen verspricht ein privates und dabei behinderten- wie altersgerechtes Wohnumfeld gepaart mit n\u00fctzlichen Dienstleistungsangeboten. Definition: Was ist Betreutes Wohnen? Betreutes Wohnen und Service-Wohnen sind\u2026","rel":"","context":"In &quot;Hilfe f\u00fcr Angeh\u00f6rige&quot;","block_context":{"text":"Hilfe f\u00fcr Angeh\u00f6rige","link":"http:\/\/www.vitalibera.org\/community\/category\/hilfe-fuer-angehoerige\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/betreuteswohnen.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6317,"url":"http:\/\/www.vitalibera.org\/community\/2026\/03\/22\/wohnungssuche-mit-einer-einschraenkung\/","url_meta":{"origin":4767,"position":4},"title":"Wohnungssuche mit einer Einschr\u00e4nkung","author":"Andreas Jecklin","date":"22 M\u00e4rz, 2026","format":false,"excerpt":"Die Suche nach einer Wohnung mit Einschr\u00e4nkungen (barrierefrei, rollstuhlg\u00e4ngig) erfordert gezielte Ma\u00dfnahmen: Nutzen Sie spezialisierte Wohnungsb\u00f6rsen (z.B.\u00a0Procap), kontaktieren Sie Behindertenverb\u00e4nde (z.B.\u00a0Pro Infirmis), das lokale Wohnungsamt f\u00fcr gef\u00f6rderten Wohnraum und beantragen Sie ggf. einen Wohnberechtigungsschein. Wichtig sind proaktive Kommunikation mit Vermietern, Besichtigung auf Barrierefreiheit (Aufzug, T\u00fcrbreiten, Dusche) und Pr\u00fcfung der Umgebung.\u00a0\u2026","rel":"","context":"In &quot;Alltag&quot;","block_context":{"text":"Alltag","link":"http:\/\/www.vitalibera.org\/community\/category\/beitraege\/eingeschraenkt-im-alltag\/alltag\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/03\/wohnungssuche.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/03\/wohnungssuche.png?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/03\/wohnungssuche.png?resize=525%2C300 1.5x"},"classes":[]},{"id":4966,"url":"http:\/\/www.vitalibera.org\/community\/2026\/01\/03\/unterschied-begleitetes-betreutes-wohnen\/","url_meta":{"origin":4767,"position":5},"title":"Unterschied : Begleitetes-\/Betreutes Wohnen","author":"Andreas Jecklin","date":"3 Januar, 2026","format":false,"excerpt":"Der Hauptunterschied liegt in der Intensit\u00e4t und Art der Unterst\u00fctzung:\u00a0Betreutes Wohnen\u00a0bietet oft umfassendere, fest integrierte Dienste (Pflege, Hauswirtschaft) in einer betreuten Wohnanlage mit Gemeinschaftsangeboten, w\u00e4hrend\u00a0begleitetes Wohnen\u00a0ambulant ist und meist nur punktuelle, bedarfsgerechte Hilfe durch Fachkr\u00e4fte zu Hause anbietet, um die Eigenst\u00e4ndigkeit zu f\u00f6rdern\u00a0\u2013 die Begriffe werden aber oft synonym oder\u2026","rel":"","context":"In &quot;Hilfe f\u00fcr Angeh\u00f6rige&quot;","block_context":{"text":"Hilfe f\u00fcr Angeh\u00f6rige","link":"http:\/\/www.vitalibera.org\/community\/category\/hilfe-fuer-angehoerige\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/01\/b2046b8b21d8633d7cbab418982b4b96.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/01\/b2046b8b21d8633d7cbab418982b4b96.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/01\/b2046b8b21d8633d7cbab418982b4b96.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/01\/b2046b8b21d8633d7cbab418982b4b96.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/01\/b2046b8b21d8633d7cbab418982b4b96.jpg?resize=1050%2C600 3x"},"classes":[]}],"jetpack_featured_media_url":"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/12\/Screenshot-2025-12-25-211635.png","_links":{"self":[{"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/posts\/4767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/comments?post=4767"}],"version-history":[{"count":0,"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/posts\/4767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/media\/4768"}],"wp:attachment":[{"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/media?parent=4767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/categories?post=4767"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/tags?post=4767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}