{"id":7339,"date":"2026-05-13T16:48:56","date_gmt":"2026-05-13T14:48:56","guid":{"rendered":"https:\/\/www.vitalibera.org\/community\/?p=7339"},"modified":"2026-05-13T16:50:51","modified_gmt":"2026-05-13T14:50:51","slug":"easyspray-spruehdosen-aufsatz","status":"publish","type":"post","link":"http:\/\/www.vitalibera.org\/community\/2026\/05\/13\/easyspray-spruehdosen-aufsatz\/","title":{"rendered":"EasySpray &#8211; Spr\u00fchdosen-Aufsatz"},"content":{"rendered":"\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"753\" height=\"806\" src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/05\/easyspray2.png\" alt=\"\" class=\"wp-image-7340 size-full\" srcset=\"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/05\/easyspray2.png 753w, http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/05\/easyspray2-280x300.png 280w\" sizes=\"(max-width: 753px) 100vw, 753px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Der EasySpray erleichtert das Bet&auml;tigen von Spr&uuml;hflaschen und Aerosoldosen. Er ersetzt das Herunterdr&uuml;cken des Spr&uuml;hkopfes durch Zusammendr&uuml;cken der Flasche. <\/p>\n\n\n\n<p>Die Bedienung ist je nach Geschicklichkeit ein- oder beidh&auml;ndig m&ouml;glich.<\/p>\n<\/div><\/div>\n\n\n\n<pre id=\"tw-target-text\" class=\"wp-block-preformatted has-base-3-background-color has-background\">Der EasySpray wird per Klettverschluss an den Flaschen befestigt und l\u00e4sst sich so einfach neu positionieren. Im Lieferumfang ist ein zus\u00e4tzliches Klettquadrat enthalten, das Sie an einer zweiten Dose verwenden k\u00f6nnen. So k\u00f6nnen Sie den EasySpray problemlos an verschiedenen Flaschen\/Dosen anbringen. <br><br>F\u00fcr die Verwendung an neuen Flaschen\/Dosen k\u00f6nnen Sie oben zus\u00e4tzliche \u201eErsatz-Klettverschl\u00fcsse\u201c erwerben. Diese enthalten jeweils zwei Flauschklettquadrate f\u00fcr die Flaschen\/Dosen und zwei Hakenstreifen zum Austauschen der Klettverschl\u00fcsse an den F\u00fc\u00dfen des EasySprays.<br><br>F\u00fcr welche Flaschen ist die Standardgr\u00f6\u00dfe geeignet? Der EasySpray eignet sich am besten f\u00fcr zylindrische Flaschen und Dosen, kann aber auch f\u00fcr Flaschen und Dosen mit gebogener Form verwendet werden. Er ist f\u00fcr verschiedene Gr\u00f6\u00dfen geeignet \u2013 von schmalen Handtaschenflaschen bis hin zu gro\u00dfen Deodorants. Es funktioniert auch auf WD40-Flaschen. Sie k\u00f6nnen es auf Aerosol- oder Spr\u00fchflaschen verwenden. <\/pre>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"351\" height=\"206\" src=\"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/04\/link1.png\" alt=\"\" class=\"wp-image-7102 size-full\" srcset=\"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/04\/link1.png 351w, http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/04\/link1-300x176.png 300w\" sizes=\"(max-width: 351px) 100vw, 351px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p><a href=\"https:\/\/www.activehands.com\/product\/easyspray\/\" target=\"_blank\" rel=\"noreferrer noopener\">Link zum Hersteller (ActiveHands)<\/a><\/p>\n<\/div><\/div>\n\n\n\n<p>ActiveHands bietet mehrer Aufs&auml;tze dieser Art an (Auch f&uuml;r kleinere Spr&uuml;hflaschen, Parf&uuml;ms etc.)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der EasySpray erleichtert das Bet\u00e4tigen von Spr\u00fchflaschen und Aerosoldosen. Er ersetzt das Herunterdr\u00fccken des Spr\u00fchkopfes durch Zusammendr\u00fccken der Flasche. Die Bedienung ist je nach Geschicklichkeit ein- oder beidh\u00e4ndig m\u00f6glich. Der EasySpray wird per Klettverschluss an den Flaschen befestigt und l\u00e4sst sich so einfach neu positionieren. Im Lieferumfang ist ein zus\u00e4tzliches Klettquadrat enthalten, das Sie an &#8230; <a title=\"EasySpray &#8211; Spr\u00fchdosen-Aufsatz\" class=\"read-more\" href=\"http:\/\/www.vitalibera.org\/community\/2026\/05\/13\/easyspray-spruehdosen-aufsatz\/\" aria-label=\"Mehr Informationen \u00fcber EasySpray &#8211; Spr\u00fchdosen-Aufsatz\">Weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":7340,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"yes","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[151],"tags":[498,519,518],"class_list":["post-7339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-heimwerken-freizeit-hobbies","tag-betroffene","tag-einhand","tag-hemiplegie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>EasySpray - Spr\u00fchdosen-Aufsatz - vitalibera.org<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"http:\/\/www.vitalibera.org\/community\/2026\/05\/13\/easyspray-spruehdosen-aufsatz\/\" \/>\r\n<meta property=\"og:locale\" content=\"de_DE\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"EasySpray - Spr\u00fchdosen-Aufsatz - vitalibera.org\" \/>\r\n<meta property=\"og:description\" content=\"Der EasySpray erleichtert das Bet\u00e4tigen von Spr\u00fchflaschen und Aerosoldosen. Er ersetzt das Herunterdr\u00fccken des Spr\u00fchkopfes durch Zusammendr\u00fccken der Flasche. Die Bedienung ist je nach Geschicklichkeit ein- oder beidh\u00e4ndig m\u00f6glich. Der EasySpray wird per Klettverschluss an den Flaschen befestigt und l\u00e4sst sich so einfach neu positionieren. Im Lieferumfang ist ein zus\u00e4tzliches Klettquadrat enthalten, das Sie an ... Weiterlesen\" \/>\r\n<meta property=\"og:url\" content=\"http:\/\/www.vitalibera.org\/community\/2026\/05\/13\/easyspray-spruehdosen-aufsatz\/\" \/>\r\n<meta property=\"og:site_name\" content=\"vitalibera.org\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/2997085857140235\" \/>\r\n<meta property=\"article:published_time\" content=\"2026-05-13T14:48:56+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2026-05-13T14:50:51+00:00\" \/>\r\n<meta property=\"og:image\" content=\"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/05\/easyspray2.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"753\" \/>\r\n\t<meta property=\"og:image:height\" content=\"806\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"author\" content=\"Andreas Jecklin\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andreas Jecklin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2026\\\/05\\\/13\\\/easyspray-spruehdosen-aufsatz\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2026\\\/05\\\/13\\\/easyspray-spruehdosen-aufsatz\\\/\"},\"author\":{\"name\":\"Andreas Jecklin\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/person\\\/6712387298421f222ff6d0a2e22c1534\"},\"headline\":\"EasySpray &#8211; Spr\u00fchdosen-Aufsatz\",\"datePublished\":\"2026-05-13T14:48:56+00:00\",\"dateModified\":\"2026-05-13T14:50:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2026\\\/05\\\/13\\\/easyspray-spruehdosen-aufsatz\\\/\"},\"wordCount\":61,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2026\\\/05\\\/13\\\/easyspray-spruehdosen-aufsatz\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/easyspray2.png\",\"keywords\":[\"betroffene\",\"einhand\",\"hemiplegie\"],\"articleSection\":[\"Heimwerken\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2026\\\/05\\\/13\\\/easyspray-spruehdosen-aufsatz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2026\\\/05\\\/13\\\/easyspray-spruehdosen-aufsatz\\\/\",\"url\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2026\\\/05\\\/13\\\/easyspray-spruehdosen-aufsatz\\\/\",\"name\":\"EasySpray - Spr\u00fchdosen-Aufsatz - vitalibera.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2026\\\/05\\\/13\\\/easyspray-spruehdosen-aufsatz\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2026\\\/05\\\/13\\\/easyspray-spruehdosen-aufsatz\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/easyspray2.png\",\"datePublished\":\"2026-05-13T14:48:56+00:00\",\"dateModified\":\"2026-05-13T14:50:51+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2026\\\/05\\\/13\\\/easyspray-spruehdosen-aufsatz\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2026\\\/05\\\/13\\\/easyspray-spruehdosen-aufsatz\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/2026\\\/05\\\/13\\\/easyspray-spruehdosen-aufsatz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EasySpray &#8211; Spr\u00fchdosen-Aufsatz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#website\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\",\"name\":\"vitalibera.org\",\"description\":\"Mit einer Einschr&auml;nkung gestaltet sich das Leben im Alltag oft schwieriger - hier berichten wir &uuml;ber unsere Erfahrungen und Hilfsmittel um den Alltag so unbeschwert und unkompliziert wie nur m&ouml;glich geniessen zu k&ouml;nnen. Dabei richten wir unseren Fokus gezielt auf Selbst&auml;ndigkeit, Eigenst&auml;ndigkeit und Selbstbestimmung.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#organization\",\"name\":\"vitalibera.org\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-banner.png\",\"contentUrl\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-banner.png\",\"width\":991,\"height\":150,\"caption\":\"vitalibera.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/2997085857140235\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/person\\\/6712387298421f222ff6d0a2e22c1534\",\"name\":\"Andreas Jecklin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/0.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"http:\\\/\\\/0.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"http:\\\/\\\/0.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Andreas Jecklin\"},\"description\":\"Manchen gab Gott die Kraft Dinge zu ver\u00e4ndern, mir gab er die Kraft zu ertragen was nicht mehr zu \u00e4ndern ist.\",\"url\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/author\\\/andy77\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EasySpray - Spr\u00fchdosen-Aufsatz - vitalibera.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.vitalibera.org\/community\/2026\/05\/13\/easyspray-spruehdosen-aufsatz\/","og_locale":"de_DE","og_type":"article","og_title":"EasySpray - Spr\u00fchdosen-Aufsatz - vitalibera.org","og_description":"Der EasySpray erleichtert das Bet\u00e4tigen von Spr\u00fchflaschen und Aerosoldosen. Er ersetzt das Herunterdr\u00fccken des Spr\u00fchkopfes durch Zusammendr\u00fccken der Flasche. Die Bedienung ist je nach Geschicklichkeit ein- oder beidh\u00e4ndig m\u00f6glich. Der EasySpray wird per Klettverschluss an den Flaschen befestigt und l\u00e4sst sich so einfach neu positionieren. Im Lieferumfang ist ein zus\u00e4tzliches Klettquadrat enthalten, das Sie an ... Weiterlesen","og_url":"http:\/\/www.vitalibera.org\/community\/2026\/05\/13\/easyspray-spruehdosen-aufsatz\/","og_site_name":"vitalibera.org","article_publisher":"https:\/\/www.facebook.com\/groups\/2997085857140235","article_published_time":"2026-05-13T14:48:56+00:00","article_modified_time":"2026-05-13T14:50:51+00:00","og_image":[{"width":753,"height":806,"url":"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/05\/easyspray2.png","type":"image\/png"}],"author":"Andreas Jecklin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Andreas Jecklin","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.vitalibera.org\/community\/2026\/05\/13\/easyspray-spruehdosen-aufsatz\/#article","isPartOf":{"@id":"http:\/\/www.vitalibera.org\/community\/2026\/05\/13\/easyspray-spruehdosen-aufsatz\/"},"author":{"name":"Andreas Jecklin","@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/person\/6712387298421f222ff6d0a2e22c1534"},"headline":"EasySpray &#8211; Spr\u00fchdosen-Aufsatz","datePublished":"2026-05-13T14:48:56+00:00","dateModified":"2026-05-13T14:50:51+00:00","mainEntityOfPage":{"@id":"http:\/\/www.vitalibera.org\/community\/2026\/05\/13\/easyspray-spruehdosen-aufsatz\/"},"wordCount":61,"commentCount":0,"publisher":{"@id":"https:\/\/www.vitalibera.org\/community\/#organization"},"image":{"@id":"http:\/\/www.vitalibera.org\/community\/2026\/05\/13\/easyspray-spruehdosen-aufsatz\/#primaryimage"},"thumbnailUrl":"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/05\/easyspray2.png","keywords":["betroffene","einhand","hemiplegie"],"articleSection":["Heimwerken"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.vitalibera.org\/community\/2026\/05\/13\/easyspray-spruehdosen-aufsatz\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.vitalibera.org\/community\/2026\/05\/13\/easyspray-spruehdosen-aufsatz\/","url":"http:\/\/www.vitalibera.org\/community\/2026\/05\/13\/easyspray-spruehdosen-aufsatz\/","name":"EasySpray - Spr\u00fchdosen-Aufsatz - vitalibera.org","isPartOf":{"@id":"https:\/\/www.vitalibera.org\/community\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.vitalibera.org\/community\/2026\/05\/13\/easyspray-spruehdosen-aufsatz\/#primaryimage"},"image":{"@id":"http:\/\/www.vitalibera.org\/community\/2026\/05\/13\/easyspray-spruehdosen-aufsatz\/#primaryimage"},"thumbnailUrl":"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/05\/easyspray2.png","datePublished":"2026-05-13T14:48:56+00:00","dateModified":"2026-05-13T14:50:51+00:00","breadcrumb":{"@id":"http:\/\/www.vitalibera.org\/community\/2026\/05\/13\/easyspray-spruehdosen-aufsatz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.vitalibera.org\/community\/2026\/05\/13\/easyspray-spruehdosen-aufsatz\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.vitalibera.org\/community\/2026\/05\/13\/easyspray-spruehdosen-aufsatz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.vitalibera.org\/community\/"},{"@type":"ListItem","position":2,"name":"EasySpray &#8211; Spr\u00fchdosen-Aufsatz"}]},{"@type":"WebSite","@id":"https:\/\/www.vitalibera.org\/community\/#website","url":"https:\/\/www.vitalibera.org\/community\/","name":"vitalibera.org","description":"Mit einer Einschr&auml;nkung gestaltet sich das Leben im Alltag oft schwieriger - hier berichten wir &uuml;ber unsere Erfahrungen und Hilfsmittel um den Alltag so unbeschwert und unkompliziert wie nur m&ouml;glich geniessen zu k&ouml;nnen. Dabei richten wir unseren Fokus gezielt auf Selbst&auml;ndigkeit, Eigenst&auml;ndigkeit und Selbstbestimmung.","publisher":{"@id":"https:\/\/www.vitalibera.org\/community\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vitalibera.org\/community\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.vitalibera.org\/community\/#organization","name":"vitalibera.org","url":"https:\/\/www.vitalibera.org\/community\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/logo\/image\/","url":"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/cropped-banner.png","contentUrl":"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/cropped-banner.png","width":991,"height":150,"caption":"vitalibera.org"},"image":{"@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/2997085857140235"]},{"@type":"Person","@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/person\/6712387298421f222ff6d0a2e22c1534","name":"Andreas Jecklin","image":{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/0.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"http:\/\/0.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"http:\/\/0.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Andreas Jecklin"},"description":"Manchen gab Gott die Kraft Dinge zu ver\u00e4ndern, mir gab er die Kraft zu ertragen was nicht mehr zu \u00e4ndern ist.","url":"http:\/\/www.vitalibera.org\/community\/author\/andy77\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":9423,"url":"http:\/\/www.vitalibera.org\/community\/2026\/09\/01\/einhaendiges-oeffnen-von-weinflaschen-mit-korken-sichere-alltagshilfe-bei-hemiparese\/","url_meta":{"origin":7339,"position":0},"title":"Einh\u00e4ndiges \u00d6ffnen von Weinflaschen mit Korken \u2013 sichere Alltagshilfe bei Hemiparese","author":"Andreas Jecklin","date":"1 September, 2026","format":false,"excerpt":"Manchmal sind es nicht die gro\u00dfen Aufgaben, sondern die kleinen Handgriffe im Alltag, die nach einer Hirnverletzung mit Hemiparese pl\u00f6tzlich kompliziert wirken. Eine Weinflasche mit Korken zu \u00f6ffnen geh\u00f6rt genau dazu: Die Flasche rutscht, der Korken sitzt fest, und die gewohnte Zweihand\u2011Technik funktioniert nicht mehr.","rel":"","context":"In &quot;Alltag&quot;","block_context":{"text":"Alltag","link":"http:\/\/www.vitalibera.org\/community\/category\/beitraege\/eingeschraenkt-im-alltag\/alltag\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/09\/wein32529.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1586,"url":"http:\/\/www.vitalibera.org\/community\/2025\/09\/11\/einhaendiger-flaschenoeffner-magnetisch\/","url_meta":{"origin":7339,"position":1},"title":"Einh\u00e4ndiger Flaschen\u00f6ffner (magnetisch)","author":"admin","date":"11 September, 2025","format":false,"excerpt":"\u00a0Trinkhilfe \/ Flaschen\u00f6ffner f\u00fcr Einh\u00e4nder Zum Angebot","rel":"","context":"In &quot;Kochen&quot;","block_context":{"text":"Kochen","link":"http:\/\/www.vitalibera.org\/community\/category\/beitraege\/eingeschraenkt-im-alltag\/alltag\/kochen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/flaschen2.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5230,"url":"http:\/\/www.vitalibera.org\/community\/2026\/01\/20\/oeffnen-einer-flasche-mit-seitlichen-druckentriegelung\/","url_meta":{"origin":7339,"position":2},"title":"\u00d6ffnen einer Flasche mit seitlichen Druckentriegelung","author":"Andreas Jecklin","date":"20 Januar, 2026","format":false,"excerpt":"Der Cap Cracker ist ein Ger\u00e4t zum \u00d6ffnen von Flaschenverschl\u00fcssen, die mit einer seitlichen Druckentriegelung versehen sind. Flaschen mit Verschl\u00fcssen, die man gleichzeitig dr\u00fccken und drehen muss, sind bei schwacher Handkraft fast unm\u00f6glich zu \u00f6ffnen. Dies macht sie f\u00fcr Menschen mit Behinderung oft unzug\u00e4nglich. Diese Verschl\u00fcsse finden Sie h\u00e4ufig auf\u2026","rel":"","context":"In &quot;Haushalt&quot;","block_context":{"text":"Haushalt","link":"http:\/\/www.vitalibera.org\/community\/category\/beitraege\/eingeschraenkt-im-alltag\/alltag\/haushalt\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/01\/Cap-Cracker-on-bottle.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/01\/Cap-Cracker-on-bottle.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/01\/Cap-Cracker-on-bottle.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/01\/Cap-Cracker-on-bottle.jpg?resize=700%2C400 2x"},"classes":[]},{"id":2869,"url":"http:\/\/www.vitalibera.org\/community\/2025\/10\/08\/2869\/","url_meta":{"origin":7339,"position":3},"title":"BarHero Flaschen\u00f6ffner","author":"admin","date":"8 Oktober, 2025","format":false,"excerpt":"Ein Griff, ein Druck und die Flasche ist offen. Mit dem\u00a0BarHero\u00a0wird jedes Bier, jede Limo und jeder Cocktail zum Erlebnis. Hergestellt aus hochwertigem Edelstahl 304 \u00fcberzeugt er nicht nur durch Langlebigkeit, sondern auch durch sein modernes, elegantes Design, das in jeder K\u00fcche und Bar ein Blickfang ist. F\u00fcr \"Einh\u00e4nder\" ein\u2026","rel":"","context":"In &quot;Alltag&quot;","block_context":{"text":"Alltag","link":"http:\/\/www.vitalibera.org\/community\/category\/beitraege\/eingeschraenkt-im-alltag\/alltag\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/flaschenoeffner1.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3137,"url":"http:\/\/www.vitalibera.org\/community\/2025\/10\/15\/flaschenhalter-ausgiesshilfe-bottle-monkey\/","url_meta":{"origin":7339,"position":4},"title":"Flaschenhalter \/ Ausgie\u00dfhilfe Bottle Monkey","author":"admin","date":"15 Oktober, 2025","format":false,"excerpt":"Dieser praktische Flaschenhalter verhindert \u00dcberschwappen, \u00dcberlaufen und Kleckern beim Einschenken und Halten von weichen PET Flaschen. Dieser praktische Flaschenhalter verhindert \u00dcberschwappen, \u00dcberlaufen und Kleckern beim Einschenken und Halten von weichen PET Flaschen. Der Flaschenhalter wird einfach auf den Falschenhals aufgeschraubt und kann mit dem Originaldeckel verschlossen werden.\u00a0 Der Flaschengriff passt\u2026","rel":"","context":"In &quot;Kochen&quot;","block_context":{"text":"Kochen","link":"http:\/\/www.vitalibera.org\/community\/category\/beitraege\/eingeschraenkt-im-alltag\/alltag\/kochen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/ausschank1.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/ausschank1.png?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/ausschank1.png?resize=525%2C300 1.5x"},"classes":[]},{"id":1342,"url":"http:\/\/www.vitalibera.org\/community\/2025\/09\/07\/schraubdeckeloeffner\/","url_meta":{"origin":7339,"position":5},"title":"Schraubdeckel\u00f6ffner","author":"admin","date":"7 September, 2025","format":false,"excerpt":"Dieser Schraubdeckel\u00f6ffner wird mit Schrauben oder mit beidseitigem Klebeband fest installiert. Er eignet sich um Gl\u00e4ser, Flaschen oder Tuben mit Schraubverschl\u00fcssen verschiedener Gr\u00f6sse unter optimalem Krafteinsatz zu \u00f6ffnen. Montiert wird der \u00d6ffner unter einem K\u00fcchenoberschrank oder idealerweise unter einer Tischplatte. Dies spart zus\u00e4tzlich Kraft und entlastet die Schulter- und Handgelenke.\u2026","rel":"","context":"In &quot;Kochen&quot;","block_context":{"text":"Kochen","link":"http:\/\/www.vitalibera.org\/community\/category\/beitraege\/eingeschraenkt-im-alltag\/alltag\/kochen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/image003-22.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/image003-22.png?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/image003-22.png?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/image003-22.png?resize=700%2C400 2x"},"classes":[]}],"jetpack_featured_media_url":"http:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/05\/easyspray2.png","_links":{"self":[{"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/posts\/7339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/comments?post=7339"}],"version-history":[{"count":0,"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/posts\/7339\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/media\/7340"}],"wp:attachment":[{"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/media?parent=7339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/categories?post=7339"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/tags?post=7339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}