{"id":8565,"date":"2026-07-14T17:00:18","date_gmt":"2026-07-14T15:00:18","guid":{"rendered":"https:\/\/www.vitalibera.org\/community\/?post_type=encyclopedia&#038;p=8565"},"modified":"2026-07-14T17:00:18","modified_gmt":"2026-07-14T15:00:18","slug":"anton-syndrom","status":"publish","type":"encyclopedia","link":"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/anton-syndrom\/","title":{"rendered":"Anton-Syndrom"},"content":{"rendered":"<p>Das Anton-Syndrom ist eine seltene neurologische St&ouml;rung, bei der Patienten vollst&auml;ndig erblinden, sich ihrer Blindheit jedoch nicht bewusst sind (visuelle <a href=\"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/anosognosie\/\" target=\"_self\" title=\"Anosognosie ist eine&nbsp;hirnorganisch bedingte Unf&auml;higkeit, die eigene Erkrankung, Behinderung oder k&ouml;rperliche Einschr&auml;nkungen (wie L&auml;hmungen oder Ged&auml;chtnisverluste) zu erkennen oder wahrzunehmen. Betroffene verhalten sich, als sei ihre Beeintr&auml;chtigung nicht vorhanden, was keine psychische Verweigerung, sondern Teil der neurologischen St&ouml;rung ist. Sie tritt oft bei Schlaganf&auml;llen, Demenz oder frontotemporaler Demenz (FTD) auf. Kernmerkmale und Symptome: Mangelnde Einsicht:&nbsp;Patienten&hellip;\" class=\"encyclopedia\">Anosognosie<\/a>). Sie leugnen den Sehverlust felsenfest, verhalten sich wie Sehende und erfinden (konfabulieren) visuelle Details, um ihre angebliche Umgebung zu beschreiben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Anton-Syndrom ist eine seltene neurologische St\u00f6rung, bei der Patienten vollst\u00e4ndig erblinden, sich ihrer Blindheit jedoch nicht bewusst sind (visuelle Anosognosie). Sie leugnen den Sehverlust felsenfest, verhalten sich wie Sehende und erfinden (konfabulieren) visuelle Details, um ihre angebliche Umgebung zu beschreiben.<\/p>\n","protected":false},"author":1,"template":"","encyclopedia-tag":[641],"class_list":["post-8565","encyclopedia","type-encyclopedia","status-publish","hentry","encyclopedia-tag-anton-syndrom"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Anton-Syndrom - vitalibera.org<\/title>\r\n<meta name=\"description\" content=\"Das Anton-Syndrom ist eine seltene neurologische St\u00f6rung, bei der Patienten vollst\u00e4ndig erblinden, sich ihrer Blindheit jedoch nicht bewusst sind (visuelle Anosognosie). Sie leugnen den Sehverlust felsenfest, verhalten sich wie Sehende und erfinden (konfabulieren) visuelle Details, um ihre angebliche Umgebung zu beschreiben.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/anton-syndrom\/\" \/>\r\n<meta property=\"og:locale\" content=\"de_DE\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Anton-Syndrom - vitalibera.org\" \/>\r\n<meta property=\"og:description\" content=\"Das Anton-Syndrom ist eine seltene neurologische St\u00f6rung, bei der Patienten vollst\u00e4ndig erblinden, sich ihrer Blindheit jedoch nicht bewusst sind (visuelle Anosognosie). Sie leugnen den Sehverlust felsenfest, verhalten sich wie Sehende und erfinden (konfabulieren) visuelle Details, um ihre angebliche Umgebung zu beschreiben.\" \/>\r\n<meta property=\"og:url\" content=\"http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/anton-syndrom\/\" \/>\r\n<meta property=\"og:site_name\" content=\"vitalibera.org\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/2997085857140235\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/enzyklopaedie\\\/anton-syndrom\\\/\",\"url\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/enzyklopaedie\\\/anton-syndrom\\\/\",\"name\":\"Anton-Syndrom - vitalibera.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#website\"},\"datePublished\":\"2026-07-14T15:00:18+00:00\",\"description\":\"Das Anton-Syndrom ist eine seltene neurologische St\u00f6rung, bei der Patienten vollst\u00e4ndig erblinden, sich ihrer Blindheit jedoch nicht bewusst sind (visuelle Anosognosie). Sie leugnen den Sehverlust felsenfest, verhalten sich wie Sehende und erfinden (konfabulieren) visuelle Details, um ihre angebliche Umgebung zu beschreiben.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/enzyklopaedie\\\/anton-syndrom\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/enzyklopaedie\\\/anton-syndrom\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/enzyklopaedie\\\/anton-syndrom\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glossar\",\"item\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/enzyklopaedie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Anton-Syndrom\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#website\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\",\"name\":\"vitalibera.org\",\"description\":\"Mit einer Einschr&auml;nkung gestaltet sich das Leben im Alltag oft schwieriger - hier berichten wir &uuml;ber unsere Erfahrungen und Hilfsmittel um den Alltag so unbeschwert und unkompliziert wie nur m&ouml;glich geniessen zu k&ouml;nnen. Dabei richten wir unseren Fokus gezielt auf Selbst&auml;ndigkeit, Eigenst&auml;ndigkeit und Selbstbestimmung.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#organization\",\"name\":\"vitalibera.org\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-banner.png\",\"contentUrl\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-banner.png\",\"width\":991,\"height\":150,\"caption\":\"vitalibera.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/2997085857140235\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anton-Syndrom - vitalibera.org","description":"Das Anton-Syndrom ist eine seltene neurologische St\u00f6rung, bei der Patienten vollst\u00e4ndig erblinden, sich ihrer Blindheit jedoch nicht bewusst sind (visuelle Anosognosie). Sie leugnen den Sehverlust felsenfest, verhalten sich wie Sehende und erfinden (konfabulieren) visuelle Details, um ihre angebliche Umgebung zu beschreiben.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/anton-syndrom\/","og_locale":"de_DE","og_type":"article","og_title":"Anton-Syndrom - vitalibera.org","og_description":"Das Anton-Syndrom ist eine seltene neurologische St\u00f6rung, bei der Patienten vollst\u00e4ndig erblinden, sich ihrer Blindheit jedoch nicht bewusst sind (visuelle Anosognosie). Sie leugnen den Sehverlust felsenfest, verhalten sich wie Sehende und erfinden (konfabulieren) visuelle Details, um ihre angebliche Umgebung zu beschreiben.","og_url":"http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/anton-syndrom\/","og_site_name":"vitalibera.org","article_publisher":"https:\/\/www.facebook.com\/groups\/2997085857140235","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/anton-syndrom\/","url":"http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/anton-syndrom\/","name":"Anton-Syndrom - vitalibera.org","isPartOf":{"@id":"https:\/\/www.vitalibera.org\/community\/#website"},"datePublished":"2026-07-14T15:00:18+00:00","description":"Das Anton-Syndrom ist eine seltene neurologische St\u00f6rung, bei der Patienten vollst\u00e4ndig erblinden, sich ihrer Blindheit jedoch nicht bewusst sind (visuelle Anosognosie). Sie leugnen den Sehverlust felsenfest, verhalten sich wie Sehende und erfinden (konfabulieren) visuelle Details, um ihre angebliche Umgebung zu beschreiben.","breadcrumb":{"@id":"http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/anton-syndrom\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/anton-syndrom\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/anton-syndrom\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.vitalibera.org\/community\/"},{"@type":"ListItem","position":2,"name":"Glossar","item":"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/"},{"@type":"ListItem","position":3,"name":"Anton-Syndrom"}]},{"@type":"WebSite","@id":"https:\/\/www.vitalibera.org\/community\/#website","url":"https:\/\/www.vitalibera.org\/community\/","name":"vitalibera.org","description":"Mit einer Einschr&auml;nkung gestaltet sich das Leben im Alltag oft schwieriger - hier berichten wir &uuml;ber unsere Erfahrungen und Hilfsmittel um den Alltag so unbeschwert und unkompliziert wie nur m&ouml;glich geniessen zu k&ouml;nnen. Dabei richten wir unseren Fokus gezielt auf Selbst&auml;ndigkeit, Eigenst&auml;ndigkeit und Selbstbestimmung.","publisher":{"@id":"https:\/\/www.vitalibera.org\/community\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vitalibera.org\/community\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.vitalibera.org\/community\/#organization","name":"vitalibera.org","url":"https:\/\/www.vitalibera.org\/community\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/logo\/image\/","url":"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/cropped-banner.png","contentUrl":"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/cropped-banner.png","width":991,"height":150,"caption":"vitalibera.org"},"image":{"@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/2997085857140235"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/encyclopedia\/8565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/encyclopedia"}],"about":[{"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/types\/encyclopedia"}],"author":[{"embeddable":true,"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/media?parent=8565"}],"wp:term":[{"taxonomy":"encyclopedia-tag","embeddable":true,"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/encyclopedia-tag?post=8565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}