{"id":8568,"date":"2026-07-14T17:10:31","date_gmt":"2026-07-14T15:10:31","guid":{"rendered":"https:\/\/www.vitalibera.org\/community\/?post_type=encyclopedia&#038;p=8568"},"modified":"2026-07-14T17:10:31","modified_gmt":"2026-07-14T15:10:31","slug":"hypothalamus","status":"publish","type":"encyclopedia","link":"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hypothalamus\/","title":{"rendered":"Hypothalamus"},"content":{"rendered":"<p>Der Hypo<a href=\"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/thalamus\/\" target=\"_self\" title=\"Der Thalamus ist ein Kerngebiet des Zwischenhirns, das als wichtigste Umschaltstation f&uuml;r fast alle Sinneseindr&uuml;cke (au&szlig;er dem Geruchssinn) dient, die auf dem Weg zur Gro&szlig;hirnrinde sind. Er wird oft als &bdquo;Tor zum Bewusstsein&ldquo; bezeichnet, da er sensorische Informationen filtert und weiterleitet. Der Thalamus ist nicht nur f&uuml;r sensorische Informationen zust&auml;ndig, sondern spielt auch eine Rolle&hellip;\" class=\"encyclopedia\">thalamus<\/a> ist eine kleine, aber lebenswichtige Schaltzentrale im Zwischenhirn. Als oberste Kontrollinstanz steuert er das <a href=\"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/vegetativ\/\" target=\"_self\" title='\"Vegetativ\" bedeutet je nach Kontext entweder&nbsp;unbewusste, automatische K&ouml;rperfunktionen, Pflanzenwachstum oder eine medizinische Zustandsbeschreibung.&nbsp;Im medizinischen Kontext bezieht es sich auf das&nbsp;autonome Nervensystem,&nbsp;das unwillk&uuml;rliche Prozesse wie Herzschlag, Atmung und Stoffwechsel steuert.&nbsp;In der Biologie bezieht sich \"vegetativ\" auf ungeschlechtliche Fortpflanzung, Pflanzenwachstum und die Ern&auml;hrung von Pflanzen.&nbsp;In der Medizin gibt es auch den Begriff des&nbsp;vegetativen Zustands&nbsp;(Wachkoma), eine schwere Gehirnsch&auml;digung,&hellip;' class=\"encyclopedia\">vegetativ<\/a>e Nervensystem sowie das <a href=\"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hormon\/\" target=\"_self\" title=\"Hormone sind k&ouml;rpereigene chemische Botenstoffe, die von verschiedenen Dr&uuml;sen und Zellen produziert und &uuml;ber das Blut im K&ouml;rper verteilt werden, um Signale zwischen Zellen zu &uuml;bertragen.&nbsp;Sie sind f&uuml;r viele lebenswichtige Prozesse wie Wachstum, Stoffwechsel, Fortpflanzung, Blutdruck und Stimmung verantwortlich und wirken auf spezifische Zielzellen, indem sie deren Funktionen beeinflussen.&nbsp;Beispiele sind Insulin zur Blutzuckerregulation oder Adrenalin&hellip;\" class=\"encyclopedia\">Hormon<\/a>system. Er reguliert grundlegende K&ouml;rperfunktionen wie den Wasser- und Salzhaushalt, die K&ouml;rpertemperatur, den Schlaf-Wach-Rhythmus, das Sexualverhalten sowie Hunger und Durst.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Hypothalamus ist eine kleine, aber lebenswichtige Schaltzentrale im Zwischenhirn. Als oberste Kontrollinstanz steuert er das vegetative Nervensystem sowie das Hormonsystem. Er reguliert grundlegende K\u00f6rperfunktionen wie den Wasser- und Salzhaushalt, die K\u00f6rpertemperatur, den Schlaf-Wach-Rhythmus, das Sexualverhalten sowie Hunger und Durst.<\/p>\n","protected":false},"author":1,"template":"","encyclopedia-tag":[],"class_list":["post-8568","encyclopedia","type-encyclopedia","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Hypothalamus - vitalibera.org<\/title>\r\n<meta name=\"description\" content=\"Der Hypothalamus ist eine kleine, aber lebenswichtige Schaltzentrale im Zwischenhirn. Als oberste Kontrollinstanz steuert er das vegetative Nervensystem sowie das Hormonsystem. Er reguliert grundlegende K\u00f6rperfunktionen wie den Wasser- und Salzhaushalt, die K\u00f6rpertemperatur, den Schlaf-Wach-Rhythmus, das Sexualverhalten sowie Hunger und Durst.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hypothalamus\/\" \/>\r\n<meta property=\"og:locale\" content=\"de_DE\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Hypothalamus - vitalibera.org\" \/>\r\n<meta property=\"og:description\" content=\"Der Hypothalamus ist eine kleine, aber lebenswichtige Schaltzentrale im Zwischenhirn. Als oberste Kontrollinstanz steuert er das vegetative Nervensystem sowie das Hormonsystem. Er reguliert grundlegende K\u00f6rperfunktionen wie den Wasser- und Salzhaushalt, die K\u00f6rpertemperatur, den Schlaf-Wach-Rhythmus, das Sexualverhalten sowie Hunger und Durst.\" \/>\r\n<meta property=\"og:url\" content=\"http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hypothalamus\/\" \/>\r\n<meta property=\"og:site_name\" content=\"vitalibera.org\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/2997085857140235\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/enzyklopaedie\\\/hypothalamus\\\/\",\"url\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/enzyklopaedie\\\/hypothalamus\\\/\",\"name\":\"Hypothalamus - vitalibera.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#website\"},\"datePublished\":\"2026-07-14T15:10:31+00:00\",\"description\":\"Der Hypothalamus ist eine kleine, aber lebenswichtige Schaltzentrale im Zwischenhirn. Als oberste Kontrollinstanz steuert er das vegetative Nervensystem sowie das Hormonsystem. Er reguliert grundlegende K\u00f6rperfunktionen wie den Wasser- und Salzhaushalt, die K\u00f6rpertemperatur, den Schlaf-Wach-Rhythmus, das Sexualverhalten sowie Hunger und Durst.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/enzyklopaedie\\\/hypothalamus\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/enzyklopaedie\\\/hypothalamus\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/enzyklopaedie\\\/hypothalamus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glossar\",\"item\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/enzyklopaedie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hypothalamus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#website\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\",\"name\":\"vitalibera.org\",\"description\":\"Mit einer Einschr&auml;nkung gestaltet sich das Leben im Alltag oft schwieriger - hier berichten wir &uuml;ber unsere Erfahrungen und Hilfsmittel um den Alltag so unbeschwert und unkompliziert wie nur m&ouml;glich geniessen zu k&ouml;nnen. Dabei richten wir unseren Fokus gezielt auf Selbst&auml;ndigkeit, Eigenst&auml;ndigkeit und Selbstbestimmung.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#organization\",\"name\":\"vitalibera.org\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-banner.png\",\"contentUrl\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-banner.png\",\"width\":991,\"height\":150,\"caption\":\"vitalibera.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/2997085857140235\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hypothalamus - vitalibera.org","description":"Der Hypothalamus ist eine kleine, aber lebenswichtige Schaltzentrale im Zwischenhirn. Als oberste Kontrollinstanz steuert er das vegetative Nervensystem sowie das Hormonsystem. Er reguliert grundlegende K\u00f6rperfunktionen wie den Wasser- und Salzhaushalt, die K\u00f6rpertemperatur, den Schlaf-Wach-Rhythmus, das Sexualverhalten sowie Hunger und Durst.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hypothalamus\/","og_locale":"de_DE","og_type":"article","og_title":"Hypothalamus - vitalibera.org","og_description":"Der Hypothalamus ist eine kleine, aber lebenswichtige Schaltzentrale im Zwischenhirn. Als oberste Kontrollinstanz steuert er das vegetative Nervensystem sowie das Hormonsystem. Er reguliert grundlegende K\u00f6rperfunktionen wie den Wasser- und Salzhaushalt, die K\u00f6rpertemperatur, den Schlaf-Wach-Rhythmus, das Sexualverhalten sowie Hunger und Durst.","og_url":"http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hypothalamus\/","og_site_name":"vitalibera.org","article_publisher":"https:\/\/www.facebook.com\/groups\/2997085857140235","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hypothalamus\/","url":"http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hypothalamus\/","name":"Hypothalamus - vitalibera.org","isPartOf":{"@id":"https:\/\/www.vitalibera.org\/community\/#website"},"datePublished":"2026-07-14T15:10:31+00:00","description":"Der Hypothalamus ist eine kleine, aber lebenswichtige Schaltzentrale im Zwischenhirn. Als oberste Kontrollinstanz steuert er das vegetative Nervensystem sowie das Hormonsystem. Er reguliert grundlegende K\u00f6rperfunktionen wie den Wasser- und Salzhaushalt, die K\u00f6rpertemperatur, den Schlaf-Wach-Rhythmus, das Sexualverhalten sowie Hunger und Durst.","breadcrumb":{"@id":"http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hypothalamus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hypothalamus\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hypothalamus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.vitalibera.org\/community\/"},{"@type":"ListItem","position":2,"name":"Glossar","item":"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/"},{"@type":"ListItem","position":3,"name":"Hypothalamus"}]},{"@type":"WebSite","@id":"https:\/\/www.vitalibera.org\/community\/#website","url":"https:\/\/www.vitalibera.org\/community\/","name":"vitalibera.org","description":"Mit einer Einschr&auml;nkung gestaltet sich das Leben im Alltag oft schwieriger - hier berichten wir &uuml;ber unsere Erfahrungen und Hilfsmittel um den Alltag so unbeschwert und unkompliziert wie nur m&ouml;glich geniessen zu k&ouml;nnen. Dabei richten wir unseren Fokus gezielt auf Selbst&auml;ndigkeit, Eigenst&auml;ndigkeit und Selbstbestimmung.","publisher":{"@id":"https:\/\/www.vitalibera.org\/community\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vitalibera.org\/community\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.vitalibera.org\/community\/#organization","name":"vitalibera.org","url":"https:\/\/www.vitalibera.org\/community\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/logo\/image\/","url":"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/cropped-banner.png","contentUrl":"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/cropped-banner.png","width":991,"height":150,"caption":"vitalibera.org"},"image":{"@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/2997085857140235"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/encyclopedia\/8568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/encyclopedia"}],"about":[{"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/types\/encyclopedia"}],"author":[{"embeddable":true,"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/media?parent=8568"}],"wp:term":[{"taxonomy":"encyclopedia-tag","embeddable":true,"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/encyclopedia-tag?post=8568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}