{"id":1207,"date":"2025-09-04T18:33:29","date_gmt":"2025-09-04T16:33:29","guid":{"rendered":"https:\/\/www.vitalibera.org\/community\/?page_id=1207"},"modified":"2025-09-04T18:47:32","modified_gmt":"2025-09-04T16:47:32","slug":"gesellschafts-und-kartenspiele","status":"publish","type":"page","link":"https:\/\/www.vitalibera.org\/community\/gesellschafts-und-kartenspiele\/","title":{"rendered":"Gesellschafts- und Kartenspiele"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"281\" height=\"180\" src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/tablegames.jpg\" alt=\"\" class=\"wp-image-1214\" style=\"width:508px;height:auto\"><\/figure>\n\n\n\n<p>blaaaaa blaaa<\/p>\n\n\n<ul class=\"wp-block-latest-posts__list has-dates wp-block-latest-posts\"><li><div class=\"wp-block-latest-posts__featured-image alignleft\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/01\/cardgames-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\"><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.vitalibera.org\/community\/2026\/01\/02\/mit-hemiparese-karten-spielen\/\">Mit Hemiparese Karten spielen<\/a><time datetime=\"2026-01-02T17:18:44+01:00\" class=\"wp-block-latest-posts__post-date\">2 Januar, 2026<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Um mit <a href=\"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hemiparese\/\" target=\"_self\" title=\"Eine Hemiparese ist eine&nbsp;L&auml;hmung einer K&ouml;rperh&auml;lfte, bei der noch eine Restaktivit&auml;t vorhanden sein kann. Eine Hemiparese entsteht durch Sch&auml;digungen im Gehirn, wie bei einem Schlaganfall oder durch einen Unfall. Es kommt zu einer Verminderung der Kraft in Gesicht, Arm und Bein in einer K&ouml;rperh&auml;lfte.\" class=\"encyclopedia\">Hemiparese<\/a> Karten zu <a href=\"https:\/\/www.vitalibera.org\/community\/2026\/08\/10\/konsole-mit-einer-hand-motorik-neu-entdecken\/\"><font color=\"blue\"><img src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/images\/link.png\" width=\"20\" height=\"20\"><u>spielen<\/u><\/font><\/a>,&nbsp;helfen&nbsp;Kartenspielhalter&nbsp;(um Karten einh&auml;ndig zu halten),&nbsp;spezielle Techniken&nbsp;zum Einhand-Handling (wie das Heben mit Daumen\/Fingern) und&nbsp;angepasste Spiele&nbsp;(z.B. Mau Mau mit Halter, Memory mit gr&ouml;&szlig;eren Karten), wobei das gezielte &Uuml;ben der betroffenen <a href=\"https:\/\/www.vitalibera.org\/community\/2026\/08\/10\/fes-und-tens-bei-spastik-und-geschlossener-hand-orientierung-nach-hirnverletzung\/\"><font color=\"blue\"><img src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/images\/link.png\" width=\"20\" height=\"20\"><u>Hand<\/u><\/font><\/a> &hellip; <a title=\"Mit Hemiparese Karten spielen\" class=\"read-more\" href=\"https:\/\/www.vitalibera.org\/community\/2026\/01\/02\/mit-hemiparese-karten-spielen\/\" aria-label=\"Mehr Informationen &uuml;ber Mit Hemiparese Karten spielen\">Weiterlesen<\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image alignleft\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/wonderpuzzle2-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\"><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.vitalibera.org\/community\/2025\/10\/10\/tetris-3d-holzpuzzle\/\">Tetris 3D Holzpuzzle<\/a><time datetime=\"2025-10-10T15:52:11+02:00\" class=\"wp-block-latest-posts__post-date\">10 Oktober, 2025<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Lieblingswunder Tetris 3D Holzpuzzle &ndash; Kreatives Lernen spielerisch entdecken Tauchen Sie ein in die faszinierende Welt des kreativen Lernens mit dem&nbsp;Lieblingswunder Tetris 3D Holzpuzzle&nbsp;! Dieses interaktive <a href=\"https:\/\/www.vitalibera.org\/community\/2026\/08\/26\/kognitives-selbsttraining-im-alltag-nach-einer-hirnverletzung-spielerisch-zurueck-zur-denkfaehigkeit\/\"><font color=\"blue\"><img src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/images\/link.png\" width=\"20\" height=\"20\"><u>Spiel<\/u><\/font><\/a> verbindet Spa&szlig; und F&ouml;rderung auf einzigartige Weise. &hellip; <a title=\"Tetris 3D Holzpuzzle\" class=\"read-more\" href=\"https:\/\/www.vitalibera.org\/community\/2025\/10\/10\/tetris-3d-holzpuzzle\/\" aria-label=\"Mehr Informationen &uuml;ber Tetris 3D Holzpuzzle\">Weiterlesen<\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/brettspiel-as-19218859-jpg-83320--150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\"><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.vitalibera.org\/community\/2025\/09\/19\/brettspiele-kartenspiele\/\">Brettspiele\/Kartenspiele<\/a><time datetime=\"2025-09-19T17:26:00+02:00\" class=\"wp-block-latest-posts__post-date\">19 September, 2025<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Gesellschaftsspiele und Kartenspiele wie beispielsweise&nbsp;UNO, Activity, Tabu oder auch Scrabble eignen sich hervorragend um sowohl Aufmerksamkeit, logisches Denken und Reaktion zu trainieren und zu f&ouml;rdern.&nbsp;Spass, Gesellschaft und kognitives <a href=\"https:\/\/www.vitalibera.org\/community\/2026\/08\/26\/simulationsspiele-als-neurologisches-eigentraining-alltagstraining-mit-struktur-planung-und-selbstwirksamkeit\/\"><font color=\"blue\"><img src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/images\/link.png\" width=\"20\" height=\"20\"><u>Training<\/u><\/font><\/a> in Einem! Activity Der erste &hellip; <a title=\"Brettspiele\/Kartenspiele\" class=\"read-more\" href=\"https:\/\/www.vitalibera.org\/community\/2025\/09\/19\/brettspiele-kartenspiele\/\" aria-label=\"Mehr Informationen &uuml;ber Brettspiele\/Kartenspiele\">Weiterlesen<\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/image001-42-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\"><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.vitalibera.org\/community\/2025\/09\/16\/ubongo-aufmerksamkeit-training-brettspiel\/\">Ubongo &ndash; Aufmerksamkeit Training (Brettspiel)<\/a><time datetime=\"2025-09-16T10:20:53+02:00\" class=\"wp-block-latest-posts__post-date\">16 September, 2025<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Und Action! Wo geh&ouml;rt denn dieses Teil hin? Warum passt das nicht? Bei &bdquo;Ubongo: Das wilde Legespiel&ldquo; spielen alle Spielerinnen und Spieler gleichzeitig. Sie legen jeweils eine Aufgabe und mehrere Legeteile vor sich ab. &hellip; <a title=\"Ubongo &ndash; Aufmerksamkeit Training (Brettspiel)\" class=\"read-more\" href=\"https:\/\/www.vitalibera.org\/community\/2025\/09\/16\/ubongo-aufmerksamkeit-training-brettspiel\/\" aria-label=\"Mehr Informationen &uuml;ber Ubongo &ndash; Aufmerksamkeit Training (Brettspiel)\">Weiterlesen<\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/image002-19-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\"><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.vitalibera.org\/community\/2025\/09\/04\/tisch-spielkartenhalter-2\/\">Tisch Spielkartenhalter<\/a><time datetime=\"2025-09-04T18:20:58+02:00\" class=\"wp-block-latest-posts__post-date\">4 September, 2025<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Zur Schonung von H&auml;nden, Armen und Schultern &uuml;bernimmt dieser h&ouml;lzerne Halter das Halten von Jass- und anderen Spielkarten. &nbsp;&nbsp; &nbsp;Zum Hersteller<\/div><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>blaaaaa blaaa<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[],"tags":[],"class_list":["post-1207","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Gesellschafts- und Kartenspiele - vitalibera.org<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.vitalibera.org\/community\/gesellschafts-und-kartenspiele\/\" \/>\r\n<meta property=\"og:locale\" content=\"de_DE\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Gesellschafts- und Kartenspiele - vitalibera.org\" \/>\r\n<meta property=\"og:description\" content=\"blaaaaa blaaa\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.vitalibera.org\/community\/gesellschafts-und-kartenspiele\/\" \/>\r\n<meta property=\"og:site_name\" content=\"vitalibera.org\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/2997085857140235\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-09-04T16:47:32+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/tablegames.jpg\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/gesellschafts-und-kartenspiele\\\/\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/gesellschafts-und-kartenspiele\\\/\",\"name\":\"Gesellschafts- und Kartenspiele - vitalibera.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/gesellschafts-und-kartenspiele\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/gesellschafts-und-kartenspiele\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/tablegames.jpg\",\"datePublished\":\"2025-09-04T16:33:29+00:00\",\"dateModified\":\"2025-09-04T16:47:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/gesellschafts-und-kartenspiele\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/gesellschafts-und-kartenspiele\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/gesellschafts-und-kartenspiele\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/tablegames.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/tablegames.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/gesellschafts-und-kartenspiele\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gesellschafts- und Kartenspiele\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#website\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\",\"name\":\"vitalibera.org\",\"description\":\"Mit einer Einschr&auml;nkung gestaltet sich das Leben im Alltag oft schwieriger - hier berichten wir &uuml;ber unsere Erfahrungen und Hilfsmittel um den Alltag so unbeschwert und unkompliziert wie nur m&ouml;glich geniessen zu k&ouml;nnen. Dabei richten wir unseren Fokus gezielt auf Selbst&auml;ndigkeit, Eigenst&auml;ndigkeit und Selbstbestimmung.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#organization\",\"name\":\"vitalibera.org\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-banner.png\",\"contentUrl\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-banner.png\",\"width\":991,\"height\":150,\"caption\":\"vitalibera.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/2997085857140235\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gesellschafts- und Kartenspiele - vitalibera.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vitalibera.org\/community\/gesellschafts-und-kartenspiele\/","og_locale":"de_DE","og_type":"article","og_title":"Gesellschafts- und Kartenspiele - vitalibera.org","og_description":"blaaaaa blaaa","og_url":"https:\/\/www.vitalibera.org\/community\/gesellschafts-und-kartenspiele\/","og_site_name":"vitalibera.org","article_publisher":"https:\/\/www.facebook.com\/groups\/2997085857140235","article_modified_time":"2025-09-04T16:47:32+00:00","og_image":[{"url":"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/tablegames.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vitalibera.org\/community\/gesellschafts-und-kartenspiele\/","url":"https:\/\/www.vitalibera.org\/community\/gesellschafts-und-kartenspiele\/","name":"Gesellschafts- und Kartenspiele - vitalibera.org","isPartOf":{"@id":"https:\/\/www.vitalibera.org\/community\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vitalibera.org\/community\/gesellschafts-und-kartenspiele\/#primaryimage"},"image":{"@id":"https:\/\/www.vitalibera.org\/community\/gesellschafts-und-kartenspiele\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/tablegames.jpg","datePublished":"2025-09-04T16:33:29+00:00","dateModified":"2025-09-04T16:47:32+00:00","breadcrumb":{"@id":"https:\/\/www.vitalibera.org\/community\/gesellschafts-und-kartenspiele\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vitalibera.org\/community\/gesellschafts-und-kartenspiele\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vitalibera.org\/community\/gesellschafts-und-kartenspiele\/#primaryimage","url":"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/tablegames.jpg","contentUrl":"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/tablegames.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vitalibera.org\/community\/gesellschafts-und-kartenspiele\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.vitalibera.org\/community\/"},{"@type":"ListItem","position":2,"name":"Gesellschafts- und Kartenspiele"}]},{"@type":"WebSite","@id":"https:\/\/www.vitalibera.org\/community\/#website","url":"https:\/\/www.vitalibera.org\/community\/","name":"vitalibera.org","description":"Mit einer Einschr&auml;nkung gestaltet sich das Leben im Alltag oft schwieriger - hier berichten wir &uuml;ber unsere Erfahrungen und Hilfsmittel um den Alltag so unbeschwert und unkompliziert wie nur m&ouml;glich geniessen zu k&ouml;nnen. Dabei richten wir unseren Fokus gezielt auf Selbst&auml;ndigkeit, Eigenst&auml;ndigkeit und Selbstbestimmung.","publisher":{"@id":"https:\/\/www.vitalibera.org\/community\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vitalibera.org\/community\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.vitalibera.org\/community\/#organization","name":"vitalibera.org","url":"https:\/\/www.vitalibera.org\/community\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/logo\/image\/","url":"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/cropped-banner.png","contentUrl":"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/cropped-banner.png","width":991,"height":150,"caption":"vitalibera.org"},"image":{"@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/2997085857140235"]}]}},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":613,"url":"https:\/\/www.vitalibera.org\/community\/freizeit-und-hobbies\/","url_meta":{"origin":1207,"position":0},"title":"Freizeit und Hobbies","author":"admin","date":"27 August, 2025","format":false,"excerpt":"Hobbies sind Freizeitaktivit\u00e4ten, die auch von Menschen mit Einschr\u00e4nkungen ausge\u00fcbt werden k\u00f6nnen und sollen.\u00a0Durch angepasste Sportger\u00e4te, spezielle Hilfsmittel wie Kartenhalter oder das Aufsuchen inklusiver Angebote wie Kunstworkshops, Gartenprojekte und offene Treffs k\u00f6nnen Menschen mit unterschiedlichen Einschr\u00e4nkungen ihre Interessen verfolgen und ihre Hobbies aus\u00fcben.Oftmals sind genau diese Aktivit\u00e4ten eine wunderbare Erg\u00e4nzung\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/08\/awesome.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/08\/awesome.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/08\/awesome.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/08\/awesome.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2272,"url":"https:\/\/www.vitalibera.org\/community\/haustiere\/","url_meta":{"origin":1207,"position":1},"title":"Haustiere","author":"admin","date":"26 September, 2025","format":false,"excerpt":"Der beste Freund des Menschen! - Ganz egal ob mit oder ohne Handicap Freunde f\u00fcrs Leben \u2013 Haustiere sind wertvolle Begleiter, gerade auch f\u00fcr Menschen mit einem HandicapNicht weniger wichtig ist die\u00a0soziale Komponente. Es ist leider eine Tatsache, dass sich viele Menschen mit Behinderungen und alte Menschen\u00a0einsam\u00a0f\u00fchlen. K\u00f6rperliche Einschr\u00e4nkungen erschweren\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/charaktere.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/charaktere.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/charaktere.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/charaktere.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":645,"url":"https:\/\/www.vitalibera.org\/community\/links\/","url_meta":{"origin":1207,"position":2},"title":"Links","author":"admin","date":"27 August, 2025","format":false,"excerpt":"Informationen, Stiftungen, Reha-Kliniken, Therapie Angebote, Hilfsmittel rund um das Thema Schlaganfall, Hirnblutung, Hirnverletzung etc. Stiftungen\u00a0 Fragile SuisseHirnverletzungen treten oft unerwartet und pl\u00f6tzlich ein. Nicht nur das Leben der Betroffenen, sondern auch das der Angeh\u00f6rigen ver\u00e4ndert sich dadurch schlagartig. FRAGILE Suisse unterst\u00fctzt Menschen mit einer Hirnverletzung und Angeh\u00f6rige mit unterschiedlichen Dienstleistungen\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/08\/link-2.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8508,"url":"https:\/\/www.vitalibera.org\/community\/neuroarena-2\/","url_meta":{"origin":1207,"position":3},"title":"NeuroArena","author":"admin","date":"6 Juli, 2026","format":false,"excerpt":"Willkommen in der NeuroArena von VitaLibera! Hier werden Konzentration, Aufmerksamkeit, Reaktionsgeschwindigkeit und geistige Flexibilit\u00e4t auf spielerische Weise trainiert. Die \u00dcbungen sind darauf ausgelegt, kognitive F\u00e4higkeiten zu f\u00f6rdern und das Gehirn aktiv herauszufordern. Viel Erfolg in der NeuroArena \u2013 jeder Klick trainiert deine Aufmerksamkeit und st\u00e4rkt deine mentale Fitness! Fokus-F\u00e4nger ist\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/07\/neuroarena.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/07\/neuroarena.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/07\/neuroarena.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/07\/neuroarena.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":639,"url":"https:\/\/www.vitalibera.org\/community\/gaming\/","url_meta":{"origin":1207,"position":4},"title":"Gaming","author":"admin","date":"27 August, 2025","format":false,"excerpt":"Gaming mit nur einer funktionierenden Arm bzw. Hand oder einem anderen Handicap ist durchaus m\u00f6glich! Zugleich kann das Spielen gleichzeitig die Aufmerksamkeit, Reaktion und Ausdauer trainieren. Auch die Spieleentwickler sowie die Hard- und Softwarehersteller haben sich zu dem Thema Inklusion beim Spielen angenommen.\"spielend Freude erleben\" verbindet, begeistert und st\u00e4rkt!\u00a0","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6876,"url":"https:\/\/www.vitalibera.org\/community\/neuroarena\/","url_meta":{"origin":1207,"position":5},"title":"NeuroArena","author":"admin","date":"22 April, 2026","format":false,"excerpt":"In der vitalibera Neuro\u202fOlympia z\u00e4hlt nicht, wer schneller oder st\u00e4rker ist \u2013 sondern wer sich selbst neu entdeckt. Jede Bewegung, jeder Gedanke, jede kleine Entscheidung ist ein Trainingsmoment f\u00fcr das eigene Nervensystem. Hier geht es um spielerische Selbstwirksamkeit: um das Wiederfinden von Energie, Fokus und Freude im Alltag. Ob im\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/04\/neuroarena9.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/pages\/1207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/comments?post=1207"}],"version-history":[{"count":0,"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/pages\/1207\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/media?parent=1207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/categories?post=1207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/tags?post=1207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}