{"id":3029,"date":"2025-10-13T21:44:20","date_gmt":"2025-10-13T19:44:20","guid":{"rendered":"https:\/\/www.vitalibera.org\/community\/?page_id=3029"},"modified":"2025-10-18T17:08:26","modified_gmt":"2025-10-18T15:08:26","slug":"informationen-fuer-angehoerige-2","status":"publish","type":"page","link":"https:\/\/www.vitalibera.org\/community\/informationen-fuer-angehoerige-2\/","title":{"rendered":"Informationen f\u00fcr Angeh\u00f6rige"},"content":{"rendered":"<ul class=\"wp-block-latest-posts__list has-dates wp-block-latest-posts\"><li><div class=\"wp-block-latest-posts__featured-image alignleft\"><a href=\"https:\/\/www.vitalibera.org\/community\/2026\/08\/31\/lagerung-nach-bobath-orientierung-fuer-angehoerige-im-alltag-bei-hemiparese\/\" aria-label=\"Lagerung nach Bobath &ndash; Orientierung f&uuml;r Angeh&ouml;rige im Alltag bei Hemiparese\"><img decoding=\"async\" width=\"150\" height=\"113\" src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/08\/lagerung082456-150x113.png\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"max-width:150px;max-height:150px;\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.vitalibera.org\/community\/2026\/08\/31\/lagerung-nach-bobath-orientierung-fuer-angehoerige-im-alltag-bei-hemiparese\/\">Lagerung nach Bobath &ndash; Orientierung f&uuml;r Angeh&ouml;rige im Alltag bei Hemiparese<\/a><time datetime=\"2026-08-31T08:28:33+02:00\" class=\"wp-block-latest-posts__post-date\">31 August, 2026<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Nach einer <a href=\"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hirnverletzung\/\" target=\"_self\" title=\"Eine Hirnverletzung (oft als&nbsp;Sch&auml;del-Hirn-Trauma, SHT) ist eine&nbsp;Sch&auml;digung des Gehirns, verursacht durch &auml;u&szlig;ere Gewalteinwirkung (Unfall, Sturz) oder innere Faktoren (Schlaganfall, Tumor). Sie f&uuml;hrt zu k&ouml;rperlichen, kognitiven und verhaltensbezogenen Einschr&auml;nkungen, die oft unsichtbar bleiben. Symptome reichen von Kopfschmerzen bis zu schweren Behinderungen. Wichtige Aspekte der Hirnverletzung: Ursachen:&nbsp;H&auml;ufig durch Schlaganf&auml;lle, Hirnblutungen, Sauerstoffmangel oder St&uuml;rze\/Verkehrsunf&auml;lle (Sch&auml;del-Hirn-Trauma). Formen (SHT):&nbsp;Unterscheidung in&hellip;\" class=\"encyclopedia\">Hirnverletzung<\/a> mit <a href=\"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hemiparese\/\" target=\"_self\" title=\"Eine Hemiparese ist eine&nbsp;L&auml;hmung einer K&ouml;rperh&auml;lfte, bei der noch eine Restaktivit&auml;t vorhanden sein kann. Eine Hemiparese entsteht durch Sch&auml;digungen im Gehirn, wie bei einem Schlaganfall oder durch einen Unfall. Es kommt zu einer Verminderung der Kraft in Gesicht, Arm und Bein in einer K&ouml;rperh&auml;lfte.\" class=\"encyclopedia\">Hemiparese<\/a> wird <a href=\"https:\/\/www.vitalibera.org\/community\/2026\/08\/31\/lagerung-nach-bobath-orientierung-fuer-angehoerige-im-alltag-bei-hemiparese\/\"><font color=\"blue\"><img src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/images\/link.png\" width=\"20\" height=\"20\"><u>Lagerung<\/u><\/font><\/a> zu einem zentralen Bestandteil des Alltags. Sie sch&uuml;tzt vor Schmerzen, Fehlstellungen und Druckstellen &ndash; und sie hilft dem Gehirn, die <a href=\"https:\/\/www.vitalibera.org\/community\/2026\/04\/19\/wenn-reize-laut-werden-und-menschen-leise\/\"><font color=\"blue\"><img src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/images\/link.png\" width=\"20\" height=\"20\"><u>betroffene<\/u><\/font><\/a> Seite wieder besser wahrzunehmen. <\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image alignleft\"><a href=\"https:\/\/www.vitalibera.org\/community\/2026\/07\/17\/wenn-das-wesen-sich-veraendert-angehoerige-zwischen-sorge-verstaendnis-und-orientierung\/\" aria-label=\"Wenn das Wesen sich ver&auml;ndert &ndash; Angeh&ouml;rige zwischen Sorge, Verst&auml;ndnis und Orientierung\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/07\/wesen2913-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"max-width:150px;max-height:150px;\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.vitalibera.org\/community\/2026\/07\/17\/wenn-das-wesen-sich-veraendert-angehoerige-zwischen-sorge-verstaendnis-und-orientierung\/\">Wenn das Wesen sich ver&auml;ndert &ndash; Angeh&ouml;rige zwischen Sorge, Verst&auml;ndnis und Orientierung<\/a><time datetime=\"2026-07-17T20:32:20+02:00\" class=\"wp-block-latest-posts__post-date\">17 Juli, 2026<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Eine Wesensver&auml;nderung nach Hirnsch&auml;digungen ist leider nicht ungew&ouml;hnlich. Sie ist oft Ausdruck der neurologischen Verletzung und nicht einer bewussten Entscheidung der betroffenen Person. F&uuml;r Angeh&ouml;rige ist es deshalb wichtig, zwischen der Erkrankung und der Person selbst zu unterscheiden.<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image alignleft\"><a href=\"https:\/\/www.vitalibera.org\/community\/2026\/07\/17\/als-angehoeriger-selbstvertrauen-und-wille-des-betroffenen-nach-hirnverletzung-aktiv-foerdern\/\" aria-label=\"Als Angeh&ouml;riger Selbstvertrauen und Wille des Betroffenen nach Hirnverletzung aktiv f&ouml;rdern\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/07\/selbstvertrauen60808-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"max-width:150px;max-height:150px;\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.vitalibera.org\/community\/2026\/07\/17\/als-angehoeriger-selbstvertrauen-und-wille-des-betroffenen-nach-hirnverletzung-aktiv-foerdern\/\">Als Angeh&ouml;riger Selbstvertrauen und Wille des Betroffenen nach Hirnverletzung aktiv f&ouml;rdern<\/a><time datetime=\"2026-07-17T16:09:34+02:00\" class=\"wp-block-latest-posts__post-date\">17 Juli, 2026<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Nach einer <a href=\"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hirnverletzung\/\" target=\"_self\" title=\"Eine Hirnverletzung (oft als&nbsp;Sch&auml;del-Hirn-Trauma, SHT) ist eine&nbsp;Sch&auml;digung des Gehirns, verursacht durch &auml;u&szlig;ere Gewalteinwirkung (Unfall, Sturz) oder innere Faktoren (Schlaganfall, Tumor). Sie f&uuml;hrt zu k&ouml;rperlichen, kognitiven und verhaltensbezogenen Einschr&auml;nkungen, die oft unsichtbar bleiben. Symptome reichen von Kopfschmerzen bis zu schweren Behinderungen. Wichtige Aspekte der Hirnverletzung: Ursachen:&nbsp;H&auml;ufig durch Schlaganf&auml;lle, Hirnblutungen, Sauerstoffmangel oder St&uuml;rze\/Verkehrsunf&auml;lle (Sch&auml;del-Hirn-Trauma). Formen (SHT):&nbsp;Unterscheidung in&hellip;\" class=\"encyclopedia\">Hirnverletzung<\/a>, einem <a href=\"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/schlaganfall\/\" target=\"_self\" title=\"Ein Schlaganfall, auch Hirnschlag oder Apoplex genannt, ist eine&nbsp;pl&ouml;tzlich auftretende Durchblutungsst&ouml;rung im Gehirn, die dazu f&uuml;hrt, dass Gehirnzellen nicht mehr ausreichend mit Sauerstoff und N&auml;hrstoffen versorgt werden.&nbsp;Dies kann zu bleibenden Sch&auml;den oder sogar zum Absterben von Hirnzellen f&uuml;hren, wenn die Durchblutung nicht schnell wiederhergestellt wird.\" class=\"encyclopedia\">Schlaganfall<\/a>, einer <a href=\"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hirnblutung\/\" target=\"_self\" title=\"Eine Hirnblutung ist eine&nbsp;Blutung innerhalb des Sch&auml;dels, die durch ein geplatztes oder gerissenes Blutgef&auml;&szlig; im Gehirn verursacht wird.&nbsp;Dies kann zu einer Sch&auml;digung des Gehirngewebes durch den Bluterguss und den erh&ouml;hten Druck f&uuml;hren, was potenziell lebensbedrohlich ist.&nbsp; Ursachen: Bluthochdruck ist eine der h&auml;ufigsten Ursachen f&uuml;r Hirnblutungen, da er die Blutgef&auml;&szlig;e schw&auml;chen und zum Platzen bringen kann.&nbsp;&hellip;\" class=\"encyclopedia\">Hirnblutung<\/a> oder einem <a href=\"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/schaedel-hirn-trauma-sht\/\" target=\"_self\" title=\"Sch&auml;del-Hirn-Trauma (SHT), eine Verletzung des Sch&auml;dels und\/oder des Gehirns, die durch eine Gewalteinwirkung verursacht wird.&nbsp;SHTs reichen von leichten Formen wie Gehirnersch&uuml;tterungen bis hin zu schweren Verletzungen, die eine sofortige medizinische Behandlung erfordern und lebensbedrohlich sein k&ouml;nnen.&nbsp;M&ouml;gliche Folgen sind vor&uuml;bergehende oder dauerhafte Einschr&auml;nkungen der Hirnfunktion sowie Blutungen.&nbsp; Ursachen &Auml;u&szlig;ere Krafteinwirkung auf den Kopf Unf&auml;lle und St&uuml;rze&hellip;\" class=\"encyclopedia\">Sch&auml;del-Hirn-Trauma<\/a> stehen Betroffene oft vor gro&szlig;en Herausforderungen. Neben k&ouml;rperlichen Einschr&auml;nkungen wie <a href=\"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hemiparese\/\" target=\"_self\" title=\"Eine Hemiparese ist eine&nbsp;L&auml;hmung einer K&ouml;rperh&auml;lfte, bei der noch eine Restaktivit&auml;t vorhanden sein kann. Eine Hemiparese entsteht durch Sch&auml;digungen im Gehirn, wie bei einem Schlaganfall oder durch einen Unfall. Es kommt zu einer Verminderung der Kraft in Gesicht, Arm und Bein in einer K&ouml;rperh&auml;lfte.\" class=\"encyclopedia\">Hemiparese<\/a>, Gangunsicherheit oder <a href=\"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/fatigue\/\" target=\"_self\" title=\"Fatigue (anhaltende Ersch&ouml;pfung) ist ein tiefgreifender, k&ouml;rperlicher und geistiger Ersch&ouml;pfungszustand. Im Gegensatz zu normaler M&uuml;digkeit bessert er sich durch Schlaf oder Ruhepausen nicht. Sie tritt h&auml;ufig als Begleitsymptom bei chronischen Erkrankungen (z. B. Gehirnverletzungen, MS oder Long-Covid) auf. Hier finden Sie eine &Uuml;bersicht &uuml;ber den Zustand: Fatigue vs. normale M&uuml;digkeit Normale M&uuml;digkeit: Tritt nach Anstrengung&hellip;\" class=\"encyclopedia\">Fatigue<\/a> &hellip; <a title=\"Als Angeh&ouml;riger Selbstvertrauen und Wille des Betroffenen nach Hirnverletzung aktiv f&ouml;rdern\" class=\"read-more\" href=\"https:\/\/www.vitalibera.org\/community\/2026\/07\/17\/als-angehoeriger-selbstvertrauen-und-wille-des-betroffenen-nach-hirnverletzung-aktiv-foerdern\/\" aria-label=\"Mehr Informationen &uuml;ber Als Angeh&ouml;riger Selbstvertrauen und Wille des Betroffenen nach Hirnverletzung aktiv f&ouml;rdern\">Weiterlesen<\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image alignleft\"><a href=\"https:\/\/www.vitalibera.org\/community\/2026\/07\/17\/hinweise-fuer-angehoerige-zum-sicheren-essen-trinken-und-zur-medikamentengabe\/\" aria-label=\"Hinweise f&uuml;r Angeh&ouml;rige zum sicheren Essen, Trinken und zur Medikamentengabe\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/07\/care-123644-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"max-width:150px;max-height:150px;\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.vitalibera.org\/community\/2026\/07\/17\/hinweise-fuer-angehoerige-zum-sicheren-essen-trinken-und-zur-medikamentengabe\/\">Hinweise f&uuml;r Angeh&ouml;rige zum sicheren Essen, Trinken und zur Medikamentengabe<\/a><time datetime=\"2026-07-17T12:37:40+02:00\" class=\"wp-block-latest-posts__post-date\">17 Juli, 2026<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Die Ern&auml;hrung und Fl&uuml;ssigkeitsaufnahme von Menschen mit einer <a href=\"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hirnverletzung\/\" target=\"_self\" title=\"Eine Hirnverletzung (oft als&nbsp;Sch&auml;del-Hirn-Trauma, SHT) ist eine&nbsp;Sch&auml;digung des Gehirns, verursacht durch &auml;u&szlig;ere Gewalteinwirkung (Unfall, Sturz) oder innere Faktoren (Schlaganfall, Tumor). Sie f&uuml;hrt zu k&ouml;rperlichen, kognitiven und verhaltensbezogenen Einschr&auml;nkungen, die oft unsichtbar bleiben. Symptome reichen von Kopfschmerzen bis zu schweren Behinderungen. Wichtige Aspekte der Hirnverletzung: Ursachen:&nbsp;H&auml;ufig durch Schlaganf&auml;lle, Hirnblutungen, Sauerstoffmangel oder St&uuml;rze\/Verkehrsunf&auml;lle (Sch&auml;del-Hirn-Trauma). Formen (SHT):&nbsp;Unterscheidung in&hellip;\" class=\"encyclopedia\">Hirnverletzung<\/a> erfordert besondere Aufmerksamkeit, insbesondere wenn zus&auml;tzlich eine <a href=\"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hemiplegie\/\" target=\"_self\" title=\"Hemiplegie ist die&nbsp;vollst&auml;ndige L&auml;hmung einer K&ouml;rperh&auml;lfte, die meist durch eine Sch&auml;digung einer Gehirnh&auml;lfte verursacht wird, oft infolge eines Schlaganfalls.&nbsp;Sie kann auch Arme, Beine und Gesichtsmuskulatur umfassen und geht oft mit einer eingeschr&auml;nkten oder aufgehobenen Sensibilit&auml;t sowie Sprachst&ouml;rungen einher.&nbsp;Die Rehabilitation konzentriert sich auf die Wiederherstellung der Bewegung durch Physiotherapie und die Vorbeugung von Komplikationen wie Muskelverk&uuml;rzungen.&nbsp;&hellip;\" class=\"encyclopedia\">Hemiplegie<\/a> (Halbseitenl&auml;hmung) und eine <a href=\"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/dysphagie\/\" target=\"_self\" title='Die Dysphagie ist gekennzeichnet durch ein&nbsp;\"Steckenbleiben\" der Nahrung in Hals oder Brust, das mit Druckgef&uuml;hl oder Schmerzen verbunden ist&nbsp;(Odynophagie). Die Beschwerden k&ouml;nnen w&auml;hrend oder nach dem Schluckakt auftreten und zervikal, retrosternal oder abdominell lokalisiert sein.' class=\"encyclopedia\">Dysphagie<\/a> (Schluckst&ouml;rung) vorliegen. Bereits &hellip; <a title=\"Hinweise f&uuml;r Angeh&ouml;rige zum sicheren Essen, Trinken und zur Medikamentengabe\" class=\"read-more\" href=\"https:\/\/www.vitalibera.org\/community\/2026\/07\/17\/hinweise-fuer-angehoerige-zum-sicheren-essen-trinken-und-zur-medikamentengabe\/\" aria-label=\"Mehr Informationen &uuml;ber Hinweise f&uuml;r Angeh&ouml;rige zum sicheren Essen, Trinken und zur Medikamentengabe\">Weiterlesen<\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image alignleft\"><a href=\"https:\/\/www.vitalibera.org\/community\/2026\/07\/16\/umgang-mit-stimmungsschwankungen-und-aggressionen-nach-einer-hirnverletzung\/\" aria-label=\"Umgang mit Stimmungsschwankungen und Aggressionen nach einer Hirnverletzung\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/07\/aggro221006-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"max-width:150px;max-height:150px;\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.vitalibera.org\/community\/2026\/07\/16\/umgang-mit-stimmungsschwankungen-und-aggressionen-nach-einer-hirnverletzung\/\">Umgang mit Stimmungsschwankungen und Aggressionen nach einer Hirnverletzung<\/a><time datetime=\"2026-07-16T22:11:16+02:00\" class=\"wp-block-latest-posts__post-date\">16 Juli, 2026<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Eine <a href=\"https:\/\/www.vitalibera.org\/community\/enzyklopaedie\/hirnverletzung\/\" target=\"_self\" title=\"Eine Hirnverletzung (oft als&nbsp;Sch&auml;del-Hirn-Trauma, SHT) ist eine&nbsp;Sch&auml;digung des Gehirns, verursacht durch &auml;u&szlig;ere Gewalteinwirkung (Unfall, Sturz) oder innere Faktoren (Schlaganfall, Tumor). Sie f&uuml;hrt zu k&ouml;rperlichen, kognitiven und verhaltensbezogenen Einschr&auml;nkungen, die oft unsichtbar bleiben. Symptome reichen von Kopfschmerzen bis zu schweren Behinderungen. Wichtige Aspekte der Hirnverletzung: Ursachen:&nbsp;H&auml;ufig durch Schlaganf&auml;lle, Hirnblutungen, Sauerstoffmangel oder St&uuml;rze\/Verkehrsunf&auml;lle (Sch&auml;del-Hirn-Trauma). Formen (SHT):&nbsp;Unterscheidung in&hellip;\" class=\"encyclopedia\">Hirnverletzung<\/a> ver&auml;ndert nicht nur das Leben der betroffenen Person, sondern stellt auch Angeh&ouml;rige vor gro&szlig;e Herausforderungen. Stimmungsschwankungen, Reizbarkeit, Aggressionen oder unbegr&uuml;ndete Vorw&uuml;rfe k&ouml;nnen &hellip; <a title=\"Umgang mit Stimmungsschwankungen und Aggressionen nach einer Hirnverletzung\" class=\"read-more\" href=\"https:\/\/www.vitalibera.org\/community\/2026\/07\/16\/umgang-mit-stimmungsschwankungen-und-aggressionen-nach-einer-hirnverletzung\/\" aria-label=\"Mehr Informationen &uuml;ber Umgang mit Stimmungsschwankungen und Aggressionen nach einer Hirnverletzung\">Weiterlesen<\/a><\/div><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[],"tags":[],"class_list":["post-3029","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Informationen f\u00fcr Angeh\u00f6rige - vitalibera.org<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"http:\/\/www.vitalibera.org\/community\/informationen-fuer-angehoerige-2\/\" \/>\r\n<meta property=\"og:locale\" content=\"de_DE\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Informationen f\u00fcr Angeh\u00f6rige - vitalibera.org\" \/>\r\n<meta property=\"og:url\" content=\"http:\/\/www.vitalibera.org\/community\/informationen-fuer-angehoerige-2\/\" \/>\r\n<meta property=\"og:site_name\" content=\"vitalibera.org\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/2997085857140235\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-10-18T15:08:26+00:00\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/informationen-fuer-angehoerige-2\\\/\",\"url\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/informationen-fuer-angehoerige-2\\\/\",\"name\":\"Informationen f\u00fcr Angeh\u00f6rige - vitalibera.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#website\"},\"datePublished\":\"2025-10-13T19:44:20+00:00\",\"dateModified\":\"2025-10-18T15:08:26+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/informationen-fuer-angehoerige-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/informationen-fuer-angehoerige-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.vitalibera.org\\\/community\\\/informationen-fuer-angehoerige-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informationen f\u00fcr Angeh\u00f6rige\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#website\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\",\"name\":\"vitalibera.org\",\"description\":\"Mit einer Einschr&auml;nkung gestaltet sich das Leben im Alltag oft schwieriger - hier berichten wir &uuml;ber unsere Erfahrungen und Hilfsmittel um den Alltag so unbeschwert und unkompliziert wie nur m&ouml;glich geniessen zu k&ouml;nnen. Dabei richten wir unseren Fokus gezielt auf Selbst&auml;ndigkeit, Eigenst&auml;ndigkeit und Selbstbestimmung.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#organization\",\"name\":\"vitalibera.org\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-banner.png\",\"contentUrl\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-banner.png\",\"width\":991,\"height\":150,\"caption\":\"vitalibera.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vitalibera.org\\\/community\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/2997085857140235\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informationen f\u00fcr Angeh\u00f6rige - vitalibera.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.vitalibera.org\/community\/informationen-fuer-angehoerige-2\/","og_locale":"de_DE","og_type":"article","og_title":"Informationen f\u00fcr Angeh\u00f6rige - vitalibera.org","og_url":"http:\/\/www.vitalibera.org\/community\/informationen-fuer-angehoerige-2\/","og_site_name":"vitalibera.org","article_publisher":"https:\/\/www.facebook.com\/groups\/2997085857140235","article_modified_time":"2025-10-18T15:08:26+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.vitalibera.org\/community\/informationen-fuer-angehoerige-2\/","url":"http:\/\/www.vitalibera.org\/community\/informationen-fuer-angehoerige-2\/","name":"Informationen f\u00fcr Angeh\u00f6rige - vitalibera.org","isPartOf":{"@id":"https:\/\/www.vitalibera.org\/community\/#website"},"datePublished":"2025-10-13T19:44:20+00:00","dateModified":"2025-10-18T15:08:26+00:00","breadcrumb":{"@id":"http:\/\/www.vitalibera.org\/community\/informationen-fuer-angehoerige-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.vitalibera.org\/community\/informationen-fuer-angehoerige-2\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.vitalibera.org\/community\/informationen-fuer-angehoerige-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.vitalibera.org\/community\/"},{"@type":"ListItem","position":2,"name":"Informationen f\u00fcr Angeh\u00f6rige"}]},{"@type":"WebSite","@id":"https:\/\/www.vitalibera.org\/community\/#website","url":"https:\/\/www.vitalibera.org\/community\/","name":"vitalibera.org","description":"Mit einer Einschr&auml;nkung gestaltet sich das Leben im Alltag oft schwieriger - hier berichten wir &uuml;ber unsere Erfahrungen und Hilfsmittel um den Alltag so unbeschwert und unkompliziert wie nur m&ouml;glich geniessen zu k&ouml;nnen. Dabei richten wir unseren Fokus gezielt auf Selbst&auml;ndigkeit, Eigenst&auml;ndigkeit und Selbstbestimmung.","publisher":{"@id":"https:\/\/www.vitalibera.org\/community\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vitalibera.org\/community\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.vitalibera.org\/community\/#organization","name":"vitalibera.org","url":"https:\/\/www.vitalibera.org\/community\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/logo\/image\/","url":"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/cropped-banner.png","contentUrl":"https:\/\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/09\/cropped-banner.png","width":991,"height":150,"caption":"vitalibera.org"},"image":{"@id":"https:\/\/www.vitalibera.org\/community\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/2997085857140235"]}]}},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":2950,"url":"https:\/\/www.vitalibera.org\/community\/informationen-fuer-angehoerige\/","url_meta":{"origin":3029,"position":0},"title":"Hilfe f\u00fcr Helfende","author":"admin","date":"12 Oktober, 2025","format":false,"excerpt":"Angeh\u00f6rige von Menschen mit Handicap sollten die Betroffenen psychisch und physisch unterst\u00fctzen, indem sie die betroffene Seite gezielt anregen, aktiv an den Therapien teilnehmen und sich nicht scheuen, bei Bedarf professionelle Hilfe und Entlastung in Anspruch zu nehmen.\u00a0Wichtige Aspekte sind dabei die Motivation, das Schaffen von Anreizen f\u00fcr die betroffene\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"Schlaganfall-Mentor","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/10\/73231221228502x20238015-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6265,"url":"https:\/\/www.vitalibera.org\/community\/wegweiser\/","url_meta":{"origin":3029,"position":1},"title":"Wegweiser","author":"admin","date":"19 M\u00e4rz, 2026","format":false,"excerpt":"Unser interaktiver Wegweiser \"Klara Kompass\" hilft dir, schnell und unkompliziert die richtigen Informationen zu finden. Egal ob du Angeh\u00f6rige\/r, Betroffene\/r oder Pflegender bist. Dabei spielt es keine Rolle in welcher Phase der Erkrankung du Unterst\u00fctzung und Informationen ben\u00f6tigst! Karla Kompass sucht die f\u00fcr dich relevanten Beitr\u00e4ge auch wenn du noch\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/03\/bc8dd8359666dc99305c3f310d264466.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/03\/bc8dd8359666dc99305c3f310d264466.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/03\/bc8dd8359666dc99305c3f310d264466.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2026\/03\/bc8dd8359666dc99305c3f310d264466.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":645,"url":"https:\/\/www.vitalibera.org\/community\/links\/","url_meta":{"origin":3029,"position":2},"title":"Links","author":"admin","date":"27 August, 2025","format":false,"excerpt":"Informationen, Stiftungen, Reha-Kliniken, Therapie Angebote, Hilfsmittel rund um das Thema Schlaganfall, Hirnblutung, Hirnverletzung etc. Stiftungen\u00a0 Fragile SuisseHirnverletzungen treten oft unerwartet und pl\u00f6tzlich ein. Nicht nur das Leben der Betroffenen, sondern auch das der Angeh\u00f6rigen ver\u00e4ndert sich dadurch schlagartig. FRAGILE Suisse unterst\u00fctzt Menschen mit einer Hirnverletzung und Angeh\u00f6rige mit unterschiedlichen Dienstleistungen\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/08\/link-2.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3031,"url":"https:\/\/www.vitalibera.org\/community\/hilfsmittel-fuer-pflegende-angehoerige\/","url_meta":{"origin":3029,"position":3},"title":"Hilfsmittel f\u00fcr pflegende Angeh\u00f6rige","author":"admin","date":"13 Oktober, 2025","format":false,"excerpt":"","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":29,"url":"https:\/\/www.vitalibera.org\/community\/welcome\/","url_meta":{"origin":3029,"position":4},"title":"Willkommen","author":"admin","date":"21 August, 2025","format":false,"excerpt":"Unsere Community richtet sich an Betroffene, die eine Hirnverletzung beispielsweise durch einen Schlaganfall, einer Hirnblutung, eines Unfalls oder eines sonstigen Schicksals erlitten haben und ihren Alltag - trotz aller widrigen Umst\u00e4nde - so normal wie nur m\u00f6glich leben wollen. Wir richten uns auch an Angeh\u00f6rige der zuvor genannten Betroffenen, die\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/08\/brain.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/08\/brain.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.vitalibera.org\/community\/wp-content\/uploads\/2025\/08\/brain.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":8946,"url":"https:\/\/www.vitalibera.org\/community\/haeufig-gestellte-fragen-von-angehoerigen\/","url_meta":{"origin":3029,"position":5},"title":"H\u00e4ufig gestellte Fragen von Angeh\u00f6rigen","author":"admin","date":"3 August, 2026","format":false,"excerpt":"","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/pages\/3029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/comments?post=3029"}],"version-history":[{"count":0,"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/pages\/3029\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/media?parent=3029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/categories?post=3029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vitalibera.org\/community\/wp-json\/wp\/v2\/tags?post=3029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}